{"id":14718,"date":"2020-03-23T19:33:33","date_gmt":"2020-03-23T18:33:33","guid":{"rendered":"https:\/\/www.hwlegend.tech\/manguste\/?p=14718"},"modified":"2020-03-23T19:33:55","modified_gmt":"2020-03-23T18:33:55","slug":"aperte-le-prenotazioni-di-sword-art-online-alicization-lycoris","status":"publish","type":"post","link":"https:\/\/www.hwlegend.tech\/games\/news\/aperte-le-prenotazioni-di-sword-art-online-alicization-lycoris\/","title":{"rendered":"Aperte le prenotazioni di Sword Art Online: Alicization Lycoris"},"content":{"rendered":"<p>E&#8217; disponibile anche un nuovo trailer di <strong><em>SWORD ART ONLINE: ALICIZATION LYCORIS<\/em><\/strong>\u00a0che d\u00e0 maggiori informazioni su storia, gameplay e personaggi!<\/p>\n<hr \/>\n<p><a href=\"https:\/\/www.hwlegend.tech\/manguste\/wp-content\/uploads\/sites\/2\/2020\/03\/Aperte-le-prenotazioni-di-Sword-Art-Online-Alicization-Lycoris.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-14721\" src=\"https:\/\/www.hwlegend.tech\/manguste\/wp-content\/uploads\/sites\/2\/2020\/03\/Aperte-le-prenotazioni-di-Sword-Art-Online-Alicization-Lycoris-1024x576.jpg\" alt=\"\" width=\"1024\" height=\"576\" srcset=\"https:\/\/www.hwlegend.tech\/games\/wp-content\/uploads\/sites\/2\/2020\/03\/Aperte-le-prenotazioni-di-Sword-Art-Online-Alicization-Lycoris-1024x576.jpg 1024w, https:\/\/www.hwlegend.tech\/games\/wp-content\/uploads\/sites\/2\/2020\/03\/Aperte-le-prenotazioni-di-Sword-Art-Online-Alicization-Lycoris-300x169.jpg 300w, https:\/\/www.hwlegend.tech\/games\/wp-content\/uploads\/sites\/2\/2020\/03\/Aperte-le-prenotazioni-di-Sword-Art-Online-Alicization-Lycoris-768x432.jpg 768w, https:\/\/www.hwlegend.tech\/games\/wp-content\/uploads\/sites\/2\/2020\/03\/Aperte-le-prenotazioni-di-Sword-Art-Online-Alicization-Lycoris.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<p>In aggiunta alle loro Sword Skill i giocatori potranno usare anche 8 diverse Sacred Art per terminare uno scontro e rispondere ai colpi dei nemici. Ogni Sacred Art ha degli effetti unici in battaglia e pu\u00f2 essere caricata per attacchi ancora pi\u00f9 forti! Sono stati anche confermati nuovi personaggi giocabili:<\/p>\n<hr \/>\n<ul>\n<li><strong>Renly Synthesis Twenty-Seven<\/strong>: fa parte degli Integrity Knights e combatte contro le forze dei Dark Territory in qualit\u00e0 di leader dell\u2019esercito dello Human Empire. Renly \u00e8 l\u2019unico personaggio che pu\u00f2 utilizzare le Twin-Wing Blade e soprattutto le \u201cTwin-Edged Wing\u201d.<\/li>\n<li><strong>Sheyta Synthesis Twelve<\/strong>: Integrity Knight conosciuta anche come Sheyta il Silent Taciturn, l\u2019Amministratrice ha dato a Sheyta un\u2019arma divina in grado di fare a pezzi ogni cosa, la Black Lily Sword.<\/li>\n<\/ul>\n<ul>\n<li><strong>Sortiliena Serlut<\/strong>: diplomatasi seconda nella sua classe della Swordcraft Academy, Sortiliena era servita da Kirito che si \u00e8 guadagnato il suo rispetto. Lei usa un proprio stile di battaglia con armi simili alle Claymore.<\/li>\n<\/ul>\n<hr \/>\n<p><iframe loading=\"lazy\" title=\"[Italiano] SWORD ART ONLINE Alicization Lycoris - Pre-Order Now - PS4\/XB1\/PC\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/CpUmcGbNuBU?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>Per la gioia dei fan,\u00a0<strong>SWORD ART ONLINE: ALICIZATION LYCORIS<\/strong>\u00a0avr\u00e0 un supporto post lancio che garantir\u00e0 un aggiornamento regolare dei contenuti. Le missioni giornaliere permetteranno ai giocatori di guadagnarsi i biglietti CUBE (che possono essere scambiati per CUBE).<\/p>\n<p>Ogni CUBE conterr\u00e0 casualmente una serie di oggetti come: costumi, decori per le armi e molto altro. I giocatori potranno anche acquistare direttamente questi oggetti tramite i SAO Coin \u2013 una valuta virtuale disponibile nel negozio in-game. Inoltre i Raid mensili includeranno 3 o 4 ore di gameplay per divertirsi con gli amici!<\/p>\n<p>Da oggi i fan possono prenotare il gioco su Xbox One e Steam! Come bonus potranno sbloccare 4 costumi del Design Contest avvenuto lo scorso settembre. Le prenotazioni della Deluxe Edition includeranno questi costumi, il Premium Pass, il Premium Pass dei costumi e 200 SAO Coin! Questi bonus saranno disponibili su Steam, Xbox One e PS4 dal 22 maggio al 22 giugno.<\/p>\n<hr \/>\n<p style=\"text-align: center\"><strong>Manguste E-Sports Teams<\/strong><\/p>\n<div class=\"gsp_post_data\" \r\n\t            data-post_type=\"post\" \r\n\t            data-cat=\"news\" \r\n\t            data-modified=\"120\"\r\n\t            data-created=\"1584992013\"\r\n\t            data-title=\"Aperte le prenotazioni di Sword Art Online: Alicization Lycoris\" \r\n\t            data-home=\"https:\/\/www.hwlegend.tech\/games\"><\/div>","protected":false},"excerpt":{"rendered":"<p>E&#8217; disponibile anche un nuovo trailer di SWORD ART ONLINE: ALICIZATION LYCORIS\u00a0che d\u00e0 maggiori informazioni su storia, gameplay e personaggi! In aggiunta alle loro Sword Skill i giocatori potranno usare anche 8 diverse Sacred Art per terminare uno scontro e rispondere ai colpi dei nemici. Ogni Sacred Art ha degli effetti unici in battaglia e [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":14719,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"class_list":["post-14718","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aperte le prenotazioni di Sword Art Online: Alicization Lycoris - HW Legend Games<\/title>\n<meta name=\"description\" content=\"E&#039; disponibile anche un nuovo trailer di SWORD ART ONLINE: ALICIZATION LYCORIS\u00a0che d\u00e0 maggiori informazioni su storia, gameplay e personaggi!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hwlegend.tech\/games\/news\/aperte-le-prenotazioni-di-sword-art-online-alicization-lycoris\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aperte le prenotazioni di Sword Art Online: Alicization Lycoris - HW Legend Games\" \/>\n<meta property=\"og:description\" content=\"E&#039; disponibile anche un nuovo trailer di SWORD ART ONLINE: ALICIZATION LYCORIS\u00a0che d\u00e0 maggiori informazioni su storia, gameplay e personaggi!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hwlegend.tech\/games\/news\/aperte-le-prenotazioni-di-sword-art-online-alicization-lycoris\/\" \/>\n<meta property=\"og:site_name\" content=\"HW Legend Games\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-23T18:33:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-23T18:33:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hwlegend.tech\/games\/wp-content\/uploads\/sites\/2\/2020\/03\/Cop-Aperte-le-prenotazioni-di-Sword-Art-Online-Alicization-Lycoris.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"555\" \/>\n\t<meta property=\"og:image:height\" content=\"410\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"djlegend\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"djlegend\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/news\\\/aperte-le-prenotazioni-di-sword-art-online-alicization-lycoris\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/news\\\/aperte-le-prenotazioni-di-sword-art-online-alicization-lycoris\\\/\"},\"author\":{\"name\":\"djlegend\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/#\\\/schema\\\/person\\\/3ed113744596ad4689eacfe0d695fcb4\"},\"headline\":\"Aperte le prenotazioni di Sword Art Online: Alicization Lycoris\",\"datePublished\":\"2020-03-23T18:33:33+00:00\",\"dateModified\":\"2020-03-23T18:33:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/news\\\/aperte-le-prenotazioni-di-sword-art-online-alicization-lycoris\\\/\"},\"wordCount\":339,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/news\\\/aperte-le-prenotazioni-di-sword-art-online-alicization-lycoris\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/03\\\/Cop-Aperte-le-prenotazioni-di-Sword-Art-Online-Alicization-Lycoris.jpg\",\"keywords\":[\"prenotazioni\",\"Sword Art Online: Alicization Lycoris\"],\"articleSection\":[\"News\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/news\\\/aperte-le-prenotazioni-di-sword-art-online-alicization-lycoris\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/news\\\/aperte-le-prenotazioni-di-sword-art-online-alicization-lycoris\\\/\",\"url\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/news\\\/aperte-le-prenotazioni-di-sword-art-online-alicization-lycoris\\\/\",\"name\":\"Aperte le prenotazioni di Sword Art Online: Alicization Lycoris - HW Legend Games\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/news\\\/aperte-le-prenotazioni-di-sword-art-online-alicization-lycoris\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/news\\\/aperte-le-prenotazioni-di-sword-art-online-alicization-lycoris\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/03\\\/Cop-Aperte-le-prenotazioni-di-Sword-Art-Online-Alicization-Lycoris.jpg\",\"datePublished\":\"2020-03-23T18:33:33+00:00\",\"dateModified\":\"2020-03-23T18:33:55+00:00\",\"description\":\"E' disponibile anche un nuovo trailer di SWORD ART ONLINE: ALICIZATION LYCORIS\u00a0che d\u00e0 maggiori informazioni su storia, gameplay e personaggi!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/news\\\/aperte-le-prenotazioni-di-sword-art-online-alicization-lycoris\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/news\\\/aperte-le-prenotazioni-di-sword-art-online-alicization-lycoris\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/news\\\/aperte-le-prenotazioni-di-sword-art-online-alicization-lycoris\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/03\\\/Cop-Aperte-le-prenotazioni-di-Sword-Art-Online-Alicization-Lycoris.jpg\",\"contentUrl\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/03\\\/Cop-Aperte-le-prenotazioni-di-Sword-Art-Online-Alicization-Lycoris.jpg\",\"width\":555,\"height\":410},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/news\\\/aperte-le-prenotazioni-di-sword-art-online-alicization-lycoris\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aperte le prenotazioni di Sword Art Online: Alicization Lycoris\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/#website\",\"url\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/\",\"name\":\"HW Legend Games\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/#organization\",\"name\":\"HW Legend Games\",\"url\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/05\\\/Logo-Manguste-trasparente.webp\",\"contentUrl\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/05\\\/Logo-Manguste-trasparente.webp\",\"width\":700,\"height\":245,\"caption\":\"HW Legend Games\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/#\\\/schema\\\/person\\\/3ed113744596ad4689eacfe0d695fcb4\",\"name\":\"djlegend\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d482afe0f6886eac7c042c0145bd9cf53427dcba7126ebb7feadae6e1c03b1ca?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d482afe0f6886eac7c042c0145bd9cf53427dcba7126ebb7feadae6e1c03b1ca?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d482afe0f6886eac7c042c0145bd9cf53427dcba7126ebb7feadae6e1c03b1ca?s=96&d=mm&r=g\",\"caption\":\"djlegend\"},\"url\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/author\\\/djlegend\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aperte le prenotazioni di Sword Art Online: Alicization Lycoris - HW Legend Games","description":"E' disponibile anche un nuovo trailer di SWORD ART ONLINE: ALICIZATION LYCORIS\u00a0che d\u00e0 maggiori informazioni su storia, gameplay e personaggi!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hwlegend.tech\/games\/news\/aperte-le-prenotazioni-di-sword-art-online-alicization-lycoris\/","og_locale":"it_IT","og_type":"article","og_title":"Aperte le prenotazioni di Sword Art Online: Alicization Lycoris - HW Legend Games","og_description":"E' disponibile anche un nuovo trailer di SWORD ART ONLINE: ALICIZATION LYCORIS\u00a0che d\u00e0 maggiori informazioni su storia, gameplay e personaggi!","og_url":"https:\/\/www.hwlegend.tech\/games\/news\/aperte-le-prenotazioni-di-sword-art-online-alicization-lycoris\/","og_site_name":"HW Legend Games","article_published_time":"2020-03-23T18:33:33+00:00","article_modified_time":"2020-03-23T18:33:55+00:00","og_image":[{"width":555,"height":410,"url":"https:\/\/www.hwlegend.tech\/games\/wp-content\/uploads\/sites\/2\/2020\/03\/Cop-Aperte-le-prenotazioni-di-Sword-Art-Online-Alicization-Lycoris.jpg","type":"image\/jpeg"}],"author":"djlegend","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"djlegend","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.hwlegend.tech\/games\/news\/aperte-le-prenotazioni-di-sword-art-online-alicization-lycoris\/#article","isPartOf":{"@id":"https:\/\/www.hwlegend.tech\/games\/news\/aperte-le-prenotazioni-di-sword-art-online-alicization-lycoris\/"},"author":{"name":"djlegend","@id":"https:\/\/www.hwlegend.tech\/games\/#\/schema\/person\/3ed113744596ad4689eacfe0d695fcb4"},"headline":"Aperte le prenotazioni di Sword Art Online: Alicization Lycoris","datePublished":"2020-03-23T18:33:33+00:00","dateModified":"2020-03-23T18:33:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.hwlegend.tech\/games\/news\/aperte-le-prenotazioni-di-sword-art-online-alicization-lycoris\/"},"wordCount":339,"commentCount":0,"publisher":{"@id":"https:\/\/www.hwlegend.tech\/games\/#organization"},"image":{"@id":"https:\/\/www.hwlegend.tech\/games\/news\/aperte-le-prenotazioni-di-sword-art-online-alicization-lycoris\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hwlegend.tech\/games\/wp-content\/uploads\/sites\/2\/2020\/03\/Cop-Aperte-le-prenotazioni-di-Sword-Art-Online-Alicization-Lycoris.jpg","keywords":["prenotazioni","Sword Art Online: Alicization Lycoris"],"articleSection":["News"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.hwlegend.tech\/games\/news\/aperte-le-prenotazioni-di-sword-art-online-alicization-lycoris\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.hwlegend.tech\/games\/news\/aperte-le-prenotazioni-di-sword-art-online-alicization-lycoris\/","url":"https:\/\/www.hwlegend.tech\/games\/news\/aperte-le-prenotazioni-di-sword-art-online-alicization-lycoris\/","name":"Aperte le prenotazioni di Sword Art Online: Alicization Lycoris - HW Legend Games","isPartOf":{"@id":"https:\/\/www.hwlegend.tech\/games\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hwlegend.tech\/games\/news\/aperte-le-prenotazioni-di-sword-art-online-alicization-lycoris\/#primaryimage"},"image":{"@id":"https:\/\/www.hwlegend.tech\/games\/news\/aperte-le-prenotazioni-di-sword-art-online-alicization-lycoris\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hwlegend.tech\/games\/wp-content\/uploads\/sites\/2\/2020\/03\/Cop-Aperte-le-prenotazioni-di-Sword-Art-Online-Alicization-Lycoris.jpg","datePublished":"2020-03-23T18:33:33+00:00","dateModified":"2020-03-23T18:33:55+00:00","description":"E' disponibile anche un nuovo trailer di SWORD ART ONLINE: ALICIZATION LYCORIS\u00a0che d\u00e0 maggiori informazioni su storia, gameplay e personaggi!","breadcrumb":{"@id":"https:\/\/www.hwlegend.tech\/games\/news\/aperte-le-prenotazioni-di-sword-art-online-alicization-lycoris\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hwlegend.tech\/games\/news\/aperte-le-prenotazioni-di-sword-art-online-alicization-lycoris\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.hwlegend.tech\/games\/news\/aperte-le-prenotazioni-di-sword-art-online-alicization-lycoris\/#primaryimage","url":"https:\/\/www.hwlegend.tech\/games\/wp-content\/uploads\/sites\/2\/2020\/03\/Cop-Aperte-le-prenotazioni-di-Sword-Art-Online-Alicization-Lycoris.jpg","contentUrl":"https:\/\/www.hwlegend.tech\/games\/wp-content\/uploads\/sites\/2\/2020\/03\/Cop-Aperte-le-prenotazioni-di-Sword-Art-Online-Alicization-Lycoris.jpg","width":555,"height":410},{"@type":"BreadcrumbList","@id":"https:\/\/www.hwlegend.tech\/games\/news\/aperte-le-prenotazioni-di-sword-art-online-alicization-lycoris\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.hwlegend.tech\/games\/"},{"@type":"ListItem","position":2,"name":"Aperte le prenotazioni di Sword Art Online: Alicization Lycoris"}]},{"@type":"WebSite","@id":"https:\/\/www.hwlegend.tech\/games\/#website","url":"https:\/\/www.hwlegend.tech\/games\/","name":"HW Legend Games","description":"","publisher":{"@id":"https:\/\/www.hwlegend.tech\/games\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hwlegend.tech\/games\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.hwlegend.tech\/games\/#organization","name":"HW Legend Games","url":"https:\/\/www.hwlegend.tech\/games\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.hwlegend.tech\/games\/#\/schema\/logo\/image\/","url":"https:\/\/www.hwlegend.tech\/games\/wp-content\/uploads\/sites\/2\/2025\/05\/Logo-Manguste-trasparente.webp","contentUrl":"https:\/\/www.hwlegend.tech\/games\/wp-content\/uploads\/sites\/2\/2025\/05\/Logo-Manguste-trasparente.webp","width":700,"height":245,"caption":"HW Legend Games"},"image":{"@id":"https:\/\/www.hwlegend.tech\/games\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.hwlegend.tech\/games\/#\/schema\/person\/3ed113744596ad4689eacfe0d695fcb4","name":"djlegend","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/d482afe0f6886eac7c042c0145bd9cf53427dcba7126ebb7feadae6e1c03b1ca?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d482afe0f6886eac7c042c0145bd9cf53427dcba7126ebb7feadae6e1c03b1ca?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d482afe0f6886eac7c042c0145bd9cf53427dcba7126ebb7feadae6e1c03b1ca?s=96&d=mm&r=g","caption":"djlegend"},"url":"https:\/\/www.hwlegend.tech\/games\/author\/djlegend\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hwlegend.tech\/games\/wp-json\/wp\/v2\/posts\/14718","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hwlegend.tech\/games\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hwlegend.tech\/games\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hwlegend.tech\/games\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hwlegend.tech\/games\/wp-json\/wp\/v2\/comments?post=14718"}],"version-history":[{"count":1,"href":"https:\/\/www.hwlegend.tech\/games\/wp-json\/wp\/v2\/posts\/14718\/revisions"}],"predecessor-version":[{"id":14722,"href":"https:\/\/www.hwlegend.tech\/games\/wp-json\/wp\/v2\/posts\/14718\/revisions\/14722"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hwlegend.tech\/games\/wp-json\/wp\/v2\/media\/14719"}],"wp:attachment":[{"href":"https:\/\/www.hwlegend.tech\/games\/wp-json\/wp\/v2\/media?parent=14718"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hwlegend.tech\/games\/wp-json\/wp\/v2\/categories?post=14718"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}