{"id":16222,"date":"2020-05-20T13:10:36","date_gmt":"2020-05-20T11:10:36","guid":{"rendered":"https:\/\/www.hwlegend.tech\/manguste\/?p=16222"},"modified":"2020-05-20T13:33:56","modified_gmt":"2020-05-20T11:33:56","slug":"svelati-ufficialmente-i-dettagli-del-tanto-atteso-gioco-mafia-trilogy","status":"publish","type":"post","link":"https:\/\/www.hwlegend.tech\/games\/news\/svelati-ufficialmente-i-dettagli-del-tanto-atteso-gioco-mafia-trilogy\/","title":{"rendered":"Svelati ufficialmente i dettagli del tanto atteso gioco Mafia Trilogy"},"content":{"rendered":"<hr \/>\n<p>2K e lo studio di sviluppo Hangar 13 annunciano oggi Mafia: Trilogy. I titoli Mafia hanno venduto 18 milioni di copie nel mondo ed ora, per la prima volta per questa generazione di console, potrete giocare tutti e 3 i titoli della serie.<\/p>\n<p><a href=\"https:\/\/www.hwlegend.tech\/manguste\/wp-content\/uploads\/sites\/2\/2020\/05\/Svelati-ufficialmente-i-dettagli-del-tanto-atteso-gioco-Mafia-Trilogy.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-16225\" src=\"https:\/\/www.hwlegend.tech\/manguste\/wp-content\/uploads\/sites\/2\/2020\/05\/Svelati-ufficialmente-i-dettagli-del-tanto-atteso-gioco-Mafia-Trilogy-1024x576.jpg\" alt=\"\" width=\"1024\" height=\"576\" srcset=\"https:\/\/www.hwlegend.tech\/games\/wp-content\/uploads\/sites\/2\/2020\/05\/Svelati-ufficialmente-i-dettagli-del-tanto-atteso-gioco-Mafia-Trilogy-1024x576.jpg 1024w, https:\/\/www.hwlegend.tech\/games\/wp-content\/uploads\/sites\/2\/2020\/05\/Svelati-ufficialmente-i-dettagli-del-tanto-atteso-gioco-Mafia-Trilogy-300x169.jpg 300w, https:\/\/www.hwlegend.tech\/games\/wp-content\/uploads\/sites\/2\/2020\/05\/Svelati-ufficialmente-i-dettagli-del-tanto-atteso-gioco-Mafia-Trilogy-768x432.jpg 768w, https:\/\/www.hwlegend.tech\/games\/wp-content\/uploads\/sites\/2\/2020\/05\/Svelati-ufficialmente-i-dettagli-del-tanto-atteso-gioco-Mafia-Trilogy-1536x864.jpg 1536w, https:\/\/www.hwlegend.tech\/games\/wp-content\/uploads\/sites\/2\/2020\/05\/Svelati-ufficialmente-i-dettagli-del-tanto-atteso-gioco-Mafia-Trilogy.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<p>Mafia: Trilogy include:<\/p>\n<hr \/>\n<ul>\n<li>Mafia: Definitive Edition \u2013 Un remake completo del gioco originale;<\/li>\n<li>Mafia II: Definitive Edition \u2013 Versione rimasterizzata in ultra HD;<\/li>\n<li>Mafia III: Definitive Edition.<\/li>\n<\/ul>\n<hr \/>\n<p>Mafia: Definitive Edition &#8211; il pezzo forte della collezione &#8211; lancia il 28 agosto un remake completo, ricostruito a partire dalle fondamenta del Mafia originale, completo di una sceneggiatura aggiornata con nuovi dialoghi, backstories ampliate e cutscenes aggiuntive; sequenze e caratteristiche di gioco completamente nuove; lo stesso motore di gioco stellare che ha alimentato la migliore cinematica di Mafia III e altri miglioramenti.<\/p>\n<p>&#8220;Mafia ha avuto un impatto forte su come i videogiochi possano raccontare storie, sappiamo quanto i fan della serie lo venerino ancora&#8221;, ha detto Haden Blackman, Presidente e CCO di Hangar 13, che ha guidato lo sviluppo di Mafia: Definitive Edition attraverso gli uffici dello studio a Brno e Praga, Repubblica Ceca; Brighton, Regno Unito; e Novato, California.<\/p>\n<p>&#8220;Quasi 20 anni dopo l&#8217;inizio della serie Mafia, abbiamo ora un&#8217;incredibile opportunit\u00e0 di presentare questo gioco a una nuova generazione di giocatori e dare ai fan di lunga data la possibilit\u00e0 di rivivere la storia di Tommy con una presentazione moderna e stellare, oltre a nuovi elementi della storia e caratteristiche di gioco&#8221;.<\/p>\n<p>Prenotando Mafia: Definitive Edition riceverai il pacchetto bonus \u201cThe Chicago Outfit\u201d. Il pacchetto include:<\/p>\n<hr \/>\n<ul>\n<li>Exclusive Player Outfit: The Don;<\/li>\n<li>Exclusive Vehicle: Smith V12 Limousine;<\/li>\n<li>Exclusive Weapon Skin: Gold Semi-Automatic.<\/li>\n<\/ul>\n<hr \/>\n<p>Inoltre i giocatori possono registrarsi qui per sbloccare i seguenti bonus:<\/p>\n<hr \/>\n<ul>\n<li>Mafia: Definitive Edition: Black Cats Motorcycle Pack;<\/li>\n<li>Mafia II: Definitive Edition: Made Man Pack;<\/li>\n<li>Mafia III: Definitive Edition: Classico Three-piece Suit &amp; IL Duca Revolver.<\/li>\n<\/ul>\n<hr \/>\n<p>Sviluppato da Hangar 13, Mafia: Trilogy dispone di classificazione PEGI 18.<\/p>\n<p><iframe loading=\"lazy\" title=\"Mafia: Definitive Edition - Coming August 28\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/-TNkX7jMjc8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p><iframe loading=\"lazy\" title=\"Mafia II: Definitive Edition - Official Launch Trailer\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/-SYB0R_AcWc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p><iframe loading=\"lazy\" title=\"Mafia III: Definitive Edition - Official Launch Trailer\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/iVQj4JzEBu0?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<hr \/>\n<p style=\"text-align: center\"><strong>Manguste E-Sports Teams<\/strong><\/p>\n<hr \/>\n<div class=\"gsp_post_data\" \r\n\t            data-post_type=\"post\" \r\n\t            data-cat=\"news\" \r\n\t            data-modified=\"120\"\r\n\t            data-created=\"1589980236\"\r\n\t            data-title=\"Svelati ufficialmente i dettagli del tanto atteso gioco Mafia Trilogy\" \r\n\t            data-home=\"https:\/\/www.hwlegend.tech\/games\"><\/div>","protected":false},"excerpt":{"rendered":"<p>2K e lo studio di sviluppo Hangar 13 annunciano oggi Mafia: Trilogy. I titoli Mafia hanno venduto 18 milioni di copie nel mondo ed ora, per la prima volta per questa generazione di console, potrete giocare tutti e 3 i titoli della serie. Mafia: Trilogy include: Mafia: Definitive Edition \u2013 Un remake completo del gioco [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":16238,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"class_list":["post-16222","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Svelati ufficialmente i dettagli del tanto atteso gioco Mafia Trilogy - HW Legend Games<\/title>\n<meta name=\"description\" content=\"2K e lo studio di sviluppo Hangar 13 annunciano ufficialmente il gioco Mafia: Trilogy. I titoli Mafia hanno venduto 18 milioni di copie nel mondo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hwlegend.tech\/games\/news\/svelati-ufficialmente-i-dettagli-del-tanto-atteso-gioco-mafia-trilogy\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Svelati ufficialmente i dettagli del tanto atteso gioco Mafia Trilogy - HW Legend Games\" \/>\n<meta property=\"og:description\" content=\"2K e lo studio di sviluppo Hangar 13 annunciano ufficialmente il gioco Mafia: Trilogy. I titoli Mafia hanno venduto 18 milioni di copie nel mondo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hwlegend.tech\/games\/news\/svelati-ufficialmente-i-dettagli-del-tanto-atteso-gioco-mafia-trilogy\/\" \/>\n<meta property=\"og:site_name\" content=\"HW Legend Games\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-20T11:10:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-20T11:33:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hwlegend.tech\/games\/wp-content\/uploads\/sites\/2\/2020\/05\/Cop-ok-Svelati-ufficialmente-i-dettagli-del-tanto-atteso-gioco-Mafia-Trilogy.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"555\" \/>\n\t<meta property=\"og:image:height\" content=\"410\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"djlegend\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"djlegend\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/news\\\/svelati-ufficialmente-i-dettagli-del-tanto-atteso-gioco-mafia-trilogy\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/news\\\/svelati-ufficialmente-i-dettagli-del-tanto-atteso-gioco-mafia-trilogy\\\/\"},\"author\":{\"name\":\"djlegend\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/#\\\/schema\\\/person\\\/3ed113744596ad4689eacfe0d695fcb4\"},\"headline\":\"Svelati ufficialmente i dettagli del tanto atteso gioco Mafia Trilogy\",\"datePublished\":\"2020-05-20T11:10:36+00:00\",\"dateModified\":\"2020-05-20T11:33:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/news\\\/svelati-ufficialmente-i-dettagli-del-tanto-atteso-gioco-mafia-trilogy\\\/\"},\"wordCount\":341,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/news\\\/svelati-ufficialmente-i-dettagli-del-tanto-atteso-gioco-mafia-trilogy\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/05\\\/Cop-ok-Svelati-ufficialmente-i-dettagli-del-tanto-atteso-gioco-Mafia-Trilogy.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/news\\\/svelati-ufficialmente-i-dettagli-del-tanto-atteso-gioco-mafia-trilogy\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/news\\\/svelati-ufficialmente-i-dettagli-del-tanto-atteso-gioco-mafia-trilogy\\\/\",\"url\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/news\\\/svelati-ufficialmente-i-dettagli-del-tanto-atteso-gioco-mafia-trilogy\\\/\",\"name\":\"Svelati ufficialmente i dettagli del tanto atteso gioco Mafia Trilogy - HW Legend Games\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/news\\\/svelati-ufficialmente-i-dettagli-del-tanto-atteso-gioco-mafia-trilogy\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/news\\\/svelati-ufficialmente-i-dettagli-del-tanto-atteso-gioco-mafia-trilogy\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/05\\\/Cop-ok-Svelati-ufficialmente-i-dettagli-del-tanto-atteso-gioco-Mafia-Trilogy.jpg\",\"datePublished\":\"2020-05-20T11:10:36+00:00\",\"dateModified\":\"2020-05-20T11:33:56+00:00\",\"description\":\"2K e lo studio di sviluppo Hangar 13 annunciano ufficialmente il gioco Mafia: Trilogy. I titoli Mafia hanno venduto 18 milioni di copie nel mondo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/news\\\/svelati-ufficialmente-i-dettagli-del-tanto-atteso-gioco-mafia-trilogy\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/news\\\/svelati-ufficialmente-i-dettagli-del-tanto-atteso-gioco-mafia-trilogy\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/news\\\/svelati-ufficialmente-i-dettagli-del-tanto-atteso-gioco-mafia-trilogy\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/05\\\/Cop-ok-Svelati-ufficialmente-i-dettagli-del-tanto-atteso-gioco-Mafia-Trilogy.jpg\",\"contentUrl\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/05\\\/Cop-ok-Svelati-ufficialmente-i-dettagli-del-tanto-atteso-gioco-Mafia-Trilogy.jpg\",\"width\":555,\"height\":410},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/news\\\/svelati-ufficialmente-i-dettagli-del-tanto-atteso-gioco-mafia-trilogy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Svelati ufficialmente i dettagli del tanto atteso gioco Mafia Trilogy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/#website\",\"url\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/\",\"name\":\"HW Legend Games\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/#organization\",\"name\":\"HW Legend Games\",\"url\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/05\\\/Logo-Manguste-trasparente.webp\",\"contentUrl\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/05\\\/Logo-Manguste-trasparente.webp\",\"width\":700,\"height\":245,\"caption\":\"HW Legend Games\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/#\\\/schema\\\/person\\\/3ed113744596ad4689eacfe0d695fcb4\",\"name\":\"djlegend\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d482afe0f6886eac7c042c0145bd9cf53427dcba7126ebb7feadae6e1c03b1ca?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d482afe0f6886eac7c042c0145bd9cf53427dcba7126ebb7feadae6e1c03b1ca?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d482afe0f6886eac7c042c0145bd9cf53427dcba7126ebb7feadae6e1c03b1ca?s=96&d=mm&r=g\",\"caption\":\"djlegend\"},\"url\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/author\\\/djlegend\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Svelati ufficialmente i dettagli del tanto atteso gioco Mafia Trilogy - HW Legend Games","description":"2K e lo studio di sviluppo Hangar 13 annunciano ufficialmente il gioco Mafia: Trilogy. I titoli Mafia hanno venduto 18 milioni di copie nel mondo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hwlegend.tech\/games\/news\/svelati-ufficialmente-i-dettagli-del-tanto-atteso-gioco-mafia-trilogy\/","og_locale":"it_IT","og_type":"article","og_title":"Svelati ufficialmente i dettagli del tanto atteso gioco Mafia Trilogy - HW Legend Games","og_description":"2K e lo studio di sviluppo Hangar 13 annunciano ufficialmente il gioco Mafia: Trilogy. I titoli Mafia hanno venduto 18 milioni di copie nel mondo.","og_url":"https:\/\/www.hwlegend.tech\/games\/news\/svelati-ufficialmente-i-dettagli-del-tanto-atteso-gioco-mafia-trilogy\/","og_site_name":"HW Legend Games","article_published_time":"2020-05-20T11:10:36+00:00","article_modified_time":"2020-05-20T11:33:56+00:00","og_image":[{"width":555,"height":410,"url":"https:\/\/www.hwlegend.tech\/games\/wp-content\/uploads\/sites\/2\/2020\/05\/Cop-ok-Svelati-ufficialmente-i-dettagli-del-tanto-atteso-gioco-Mafia-Trilogy.jpg","type":"image\/jpeg"}],"author":"djlegend","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"djlegend","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.hwlegend.tech\/games\/news\/svelati-ufficialmente-i-dettagli-del-tanto-atteso-gioco-mafia-trilogy\/#article","isPartOf":{"@id":"https:\/\/www.hwlegend.tech\/games\/news\/svelati-ufficialmente-i-dettagli-del-tanto-atteso-gioco-mafia-trilogy\/"},"author":{"name":"djlegend","@id":"https:\/\/www.hwlegend.tech\/games\/#\/schema\/person\/3ed113744596ad4689eacfe0d695fcb4"},"headline":"Svelati ufficialmente i dettagli del tanto atteso gioco Mafia Trilogy","datePublished":"2020-05-20T11:10:36+00:00","dateModified":"2020-05-20T11:33:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.hwlegend.tech\/games\/news\/svelati-ufficialmente-i-dettagli-del-tanto-atteso-gioco-mafia-trilogy\/"},"wordCount":341,"commentCount":0,"publisher":{"@id":"https:\/\/www.hwlegend.tech\/games\/#organization"},"image":{"@id":"https:\/\/www.hwlegend.tech\/games\/news\/svelati-ufficialmente-i-dettagli-del-tanto-atteso-gioco-mafia-trilogy\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hwlegend.tech\/games\/wp-content\/uploads\/sites\/2\/2020\/05\/Cop-ok-Svelati-ufficialmente-i-dettagli-del-tanto-atteso-gioco-Mafia-Trilogy.jpg","articleSection":["News"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.hwlegend.tech\/games\/news\/svelati-ufficialmente-i-dettagli-del-tanto-atteso-gioco-mafia-trilogy\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.hwlegend.tech\/games\/news\/svelati-ufficialmente-i-dettagli-del-tanto-atteso-gioco-mafia-trilogy\/","url":"https:\/\/www.hwlegend.tech\/games\/news\/svelati-ufficialmente-i-dettagli-del-tanto-atteso-gioco-mafia-trilogy\/","name":"Svelati ufficialmente i dettagli del tanto atteso gioco Mafia Trilogy - HW Legend Games","isPartOf":{"@id":"https:\/\/www.hwlegend.tech\/games\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hwlegend.tech\/games\/news\/svelati-ufficialmente-i-dettagli-del-tanto-atteso-gioco-mafia-trilogy\/#primaryimage"},"image":{"@id":"https:\/\/www.hwlegend.tech\/games\/news\/svelati-ufficialmente-i-dettagli-del-tanto-atteso-gioco-mafia-trilogy\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hwlegend.tech\/games\/wp-content\/uploads\/sites\/2\/2020\/05\/Cop-ok-Svelati-ufficialmente-i-dettagli-del-tanto-atteso-gioco-Mafia-Trilogy.jpg","datePublished":"2020-05-20T11:10:36+00:00","dateModified":"2020-05-20T11:33:56+00:00","description":"2K e lo studio di sviluppo Hangar 13 annunciano ufficialmente il gioco Mafia: Trilogy. I titoli Mafia hanno venduto 18 milioni di copie nel mondo.","breadcrumb":{"@id":"https:\/\/www.hwlegend.tech\/games\/news\/svelati-ufficialmente-i-dettagli-del-tanto-atteso-gioco-mafia-trilogy\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hwlegend.tech\/games\/news\/svelati-ufficialmente-i-dettagli-del-tanto-atteso-gioco-mafia-trilogy\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.hwlegend.tech\/games\/news\/svelati-ufficialmente-i-dettagli-del-tanto-atteso-gioco-mafia-trilogy\/#primaryimage","url":"https:\/\/www.hwlegend.tech\/games\/wp-content\/uploads\/sites\/2\/2020\/05\/Cop-ok-Svelati-ufficialmente-i-dettagli-del-tanto-atteso-gioco-Mafia-Trilogy.jpg","contentUrl":"https:\/\/www.hwlegend.tech\/games\/wp-content\/uploads\/sites\/2\/2020\/05\/Cop-ok-Svelati-ufficialmente-i-dettagli-del-tanto-atteso-gioco-Mafia-Trilogy.jpg","width":555,"height":410},{"@type":"BreadcrumbList","@id":"https:\/\/www.hwlegend.tech\/games\/news\/svelati-ufficialmente-i-dettagli-del-tanto-atteso-gioco-mafia-trilogy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.hwlegend.tech\/games\/"},{"@type":"ListItem","position":2,"name":"Svelati ufficialmente i dettagli del tanto atteso gioco Mafia Trilogy"}]},{"@type":"WebSite","@id":"https:\/\/www.hwlegend.tech\/games\/#website","url":"https:\/\/www.hwlegend.tech\/games\/","name":"HW Legend Games","description":"","publisher":{"@id":"https:\/\/www.hwlegend.tech\/games\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hwlegend.tech\/games\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.hwlegend.tech\/games\/#organization","name":"HW Legend Games","url":"https:\/\/www.hwlegend.tech\/games\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.hwlegend.tech\/games\/#\/schema\/logo\/image\/","url":"https:\/\/www.hwlegend.tech\/games\/wp-content\/uploads\/sites\/2\/2025\/05\/Logo-Manguste-trasparente.webp","contentUrl":"https:\/\/www.hwlegend.tech\/games\/wp-content\/uploads\/sites\/2\/2025\/05\/Logo-Manguste-trasparente.webp","width":700,"height":245,"caption":"HW Legend Games"},"image":{"@id":"https:\/\/www.hwlegend.tech\/games\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.hwlegend.tech\/games\/#\/schema\/person\/3ed113744596ad4689eacfe0d695fcb4","name":"djlegend","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/d482afe0f6886eac7c042c0145bd9cf53427dcba7126ebb7feadae6e1c03b1ca?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d482afe0f6886eac7c042c0145bd9cf53427dcba7126ebb7feadae6e1c03b1ca?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d482afe0f6886eac7c042c0145bd9cf53427dcba7126ebb7feadae6e1c03b1ca?s=96&d=mm&r=g","caption":"djlegend"},"url":"https:\/\/www.hwlegend.tech\/games\/author\/djlegend\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hwlegend.tech\/games\/wp-json\/wp\/v2\/posts\/16222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hwlegend.tech\/games\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hwlegend.tech\/games\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hwlegend.tech\/games\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hwlegend.tech\/games\/wp-json\/wp\/v2\/comments?post=16222"}],"version-history":[{"count":2,"href":"https:\/\/www.hwlegend.tech\/games\/wp-json\/wp\/v2\/posts\/16222\/revisions"}],"predecessor-version":[{"id":16226,"href":"https:\/\/www.hwlegend.tech\/games\/wp-json\/wp\/v2\/posts\/16222\/revisions\/16226"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hwlegend.tech\/games\/wp-json\/wp\/v2\/media\/16238"}],"wp:attachment":[{"href":"https:\/\/www.hwlegend.tech\/games\/wp-json\/wp\/v2\/media?parent=16222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hwlegend.tech\/games\/wp-json\/wp\/v2\/categories?post=16222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}