{"id":16327,"date":"2020-05-25T19:50:28","date_gmt":"2020-05-25T17:50:28","guid":{"rendered":"https:\/\/www.hwlegend.tech\/manguste\/?p=16327"},"modified":"2020-05-25T19:51:19","modified_gmt":"2020-05-25T17:51:19","slug":"la-nazionale-italiana-in-pes-2020-e-risultata-campione-deuropa","status":"publish","type":"post","link":"https:\/\/www.hwlegend.tech\/games\/news\/la-nazionale-italiana-in-pes-2020-e-risultata-campione-deuropa\/","title":{"rendered":"La nazionale italiana in PES 2020 \u00e8 risultata campione d&#8217;Europa"},"content":{"rendered":"<hr \/>\n<p>Un risultato straordinario quello ottenuto dalla eNazionale TIMVISION PES, che dopo aver superato ieri in pompa magna la fase a gironi ha messo in fila oggi Israele, Francia e Serbia, consentendo alla FIGC di conquistare il suo primo trofeo nel mondo dell&#8217;eFoot. Decisivo il gol di un&#8217;inedita coppia di scuola napoletana, quella formata dall&#8217;eplayer Carmine &#8216;Naples17x&#8217; Liuzzi e dall&#8217;avatar di Lorenzo Insigne, che al novantesimo minuto ha risolto la quarta e ultima partita della finale con i serbi.<\/p>\n<p><a href=\"https:\/\/www.hwlegend.tech\/manguste\/wp-content\/uploads\/sites\/2\/2020\/05\/La-nazionale-italiana-in-PES-2020-\u00e8-risultata-campione-dEuropa.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-16329\" src=\"https:\/\/www.hwlegend.tech\/manguste\/wp-content\/uploads\/sites\/2\/2020\/05\/La-nazionale-italiana-in-PES-2020-\u00e8-risultata-campione-dEuropa.jpg\" alt=\"\" width=\"1000\" height=\"1000\" srcset=\"https:\/\/www.hwlegend.tech\/games\/wp-content\/uploads\/sites\/2\/2020\/05\/La-nazionale-italiana-in-PES-2020-\u00e8-risultata-campione-dEuropa.jpg 1000w, https:\/\/www.hwlegend.tech\/games\/wp-content\/uploads\/sites\/2\/2020\/05\/La-nazionale-italiana-in-PES-2020-\u00e8-risultata-campione-dEuropa-300x300.jpg 300w, https:\/\/www.hwlegend.tech\/games\/wp-content\/uploads\/sites\/2\/2020\/05\/La-nazionale-italiana-in-PES-2020-\u00e8-risultata-campione-dEuropa-150x150.jpg 150w, https:\/\/www.hwlegend.tech\/games\/wp-content\/uploads\/sites\/2\/2020\/05\/La-nazionale-italiana-in-PES-2020-\u00e8-risultata-campione-dEuropa-768x768.jpg 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>\n<p>Posticipato di un anno l&#8217;Europeo di calcio per l&#8217;emergenza Covid-19, l&#8217;Italia pu\u00f2 intanto festeggiare il successo nel torneo virtuale che in questo week end ha visto affrontarsi online le 16 nazionali finaliste. Merito dei quattro eplayer azzurri &#8211; Rosario &#8216;Npk_02&#8217; Accurso, Nicola &#8216;nicaldan&#8217; Lillo, Carmine &#8216;Naples17x&#8217; Liuzzi e Alfonso &#8216;AlonsoGrayfox&#8217; Mereu &#8211; protagonisti di una cavalcata trionfale suggellata dal successo in finale sulla Serbia, gi\u00e0 battuta ieri nella fase a gironi.<\/p>\n<p>A regalare il primo titolo della sua giovane storia all&#8217;Italia sono state le vittorie di Alfonso &#8216;AlonsoGrayfox&#8217; Mereu su &#8216;roksaczv22&#8217; (4-2 con tripletta di Immobile e gol di Quagliarella), di Nicola &#8216;nicaldan&#8217; Lillo su &#8216;roksaczv22&#8217; (1-0, gol partita di Immobile) e quella decisiva di Carmine &#8216;Naples17x&#8217; Liuzzi su &#8216;Kepa_PFC&#8217;, 2-1 con il gol di Lorenzo Insigne allo scadere a decidere un match tiratissimo, che ha reso ininfluente la sconfitta di Rosario &#8216;Npk_02&#8217; Accurso.<\/p>\n<p>Avvincente e ricca di colpi di scena anche la semifinale con la Francia, indicata alla vigilia come la grande favorita per la vittoria dell&#8217;Europeo. Nella prima partita Carmine &#8216;Naples17x&#8217; Liuzzi \u00e8 riuscito a battere 2-1 il tre volte Campione del Mondo &#8216;usmakabyle&#8217; grazie alla rete realizzata a due minuti dallo scadere dei tempi supplementari da Lorenzo Pellegrini. Ancora pi\u00f9 emozionante la seconda sfida tra il capitano azzurro Nicola &#8216;nicaldan&#8217; Lillo e &#8216;lofti_derradji&#8217;, vinta dall&#8217;Italia ai rigori in un remake della finale che 14 anni fa a Berlino ha regalato alla Nazionale di Marcello Lippi la quarta Coppa del Mondo.<\/p>\n<p>In vantaggio per 3-1 con i gol di Zaniolo, Belotti e Immobile, &#8216;nicaldan&#8217; si \u00e8 visto raggiungere nella ripresa dalla doppietta di Fekir. I rigori hanno spalancato all&#8217;Italia le porte della finale, ultimo atto di un torneo che in mattinata aveva visto la eNazionale TIMVISION PES superare per due partite a zero Israele in virt\u00f9 delle vittorie di Alfonso &#8216;AlonsoGrayfox&#8217; Mereu su &#8216;Oreldi23&#8217; (1-0 con gol di Belotti) e di Rosario &#8216;Npk_02&#8217; Accurso su &#8216;Nym_Astam&#8217;, (4-0 frutto della doppietta di Zaniolo e delle reti di Quagliarella e Florenzi).<\/p>\n<p>Si chiude cos\u00ec un week end da incorniciare per i colori azzurri, iniziato ieri con il primo posto nel girone ottenuto grazie alle vittorie su Danimarca (5-1) e Serbia (6-5). E proprio la Serbia, qualificata ai Quarti di finale come seconda classificata del Gruppo B, \u00e8 stata costretta ad arrendersi per la seconda volta nel giro di 24 ore ad un&#8217;Italia che pu\u00f2 scrivere cos\u00ec il proprio nome nella storia dell&#8217;eFoot.<\/p>\n<hr \/>\n<p><span style=\"font-size: 14pt;color: #0000ff\"><strong>Quarti di finale<\/strong><\/span><\/p>\n<hr \/>\n<p>Olanda-Romania 1-2;<br \/>\nSpagna-Serbia 1-2;<br \/>\nITALIA-Israele 2-0;<br \/>\nFrancia-Croazia 2-0.<\/p>\n<hr \/>\n<p><span style=\"font-size: 14pt;color: #0000ff\"><strong>Semifinali<\/strong><\/span><\/p>\n<hr \/>\n<p>ITALIA-Francia 2-0;<br \/>\nSerbia-Romania 2-1.<\/p>\n<hr \/>\n<p><span style=\"font-size: 14pt;color: #0000ff\"><strong>Finale<\/strong><\/span><\/p>\n<hr \/>\n<p>ITALIA-Serbia 3-1.<\/p>\n<hr \/>\n<p style=\"text-align: center\"><strong>Manguste E-Sports Teams<\/strong><\/p>\n<hr \/>\n<div class=\"gsp_post_data\" \r\n\t            data-post_type=\"post\" \r\n\t            data-cat=\"news\" \r\n\t            data-modified=\"120\"\r\n\t            data-created=\"1590436228\"\r\n\t            data-title=\"La nazionale italiana in PES 2020 \u00e8 risultata campione d&#8217;Europa\" \r\n\t            data-home=\"https:\/\/www.hwlegend.tech\/games\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Un risultato straordinario quello ottenuto dalla eNazionale TIMVISION PES, che dopo aver superato ieri in pompa magna la fase a gironi ha messo in fila oggi Israele, Francia e Serbia, consentendo alla FIGC di conquistare il suo primo trofeo nel mondo dell&#8217;eFoot. Decisivo il gol di un&#8217;inedita coppia di scuola napoletana, quella formata dall&#8217;eplayer Carmine [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":16328,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"class_list":["post-16327","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La nazionale italiana in PES 2020 \u00e8 risultata campione d&#039;Europa - HW Legend Games<\/title>\n<meta name=\"description\" content=\"Un risultato straordinario quello ottenuto dalla eNazionale TIMVISION PES, consentendo alla FIGC di conquistare il suo primo trofeo nel mondo dell&#039;eFoot.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hwlegend.tech\/games\/news\/la-nazionale-italiana-in-pes-2020-e-risultata-campione-deuropa\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La nazionale italiana in PES 2020 \u00e8 risultata campione d&#039;Europa - HW Legend Games\" \/>\n<meta property=\"og:description\" content=\"Un risultato straordinario quello ottenuto dalla eNazionale TIMVISION PES, consentendo alla FIGC di conquistare il suo primo trofeo nel mondo dell&#039;eFoot.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hwlegend.tech\/games\/news\/la-nazionale-italiana-in-pes-2020-e-risultata-campione-deuropa\/\" \/>\n<meta property=\"og:site_name\" content=\"HW Legend Games\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-25T17:50:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-25T17:51:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hwlegend.tech\/games\/wp-content\/uploads\/sites\/2\/2020\/05\/Cop-La-nazionale-italiana-in-PES-2020-\u00e8-risultata-campione-dEuropa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"555\" \/>\n\t<meta property=\"og:image:height\" content=\"410\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"djlegend\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"djlegend\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/news\\\/la-nazionale-italiana-in-pes-2020-e-risultata-campione-deuropa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/news\\\/la-nazionale-italiana-in-pes-2020-e-risultata-campione-deuropa\\\/\"},\"author\":{\"name\":\"djlegend\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/#\\\/schema\\\/person\\\/3ed113744596ad4689eacfe0d695fcb4\"},\"headline\":\"La nazionale italiana in PES 2020 \u00e8 risultata campione d&#8217;Europa\",\"datePublished\":\"2020-05-25T17:50:28+00:00\",\"dateModified\":\"2020-05-25T17:51:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/news\\\/la-nazionale-italiana-in-pes-2020-e-risultata-campione-deuropa\\\/\"},\"wordCount\":525,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/news\\\/la-nazionale-italiana-in-pes-2020-e-risultata-campione-deuropa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/05\\\/Cop-La-nazionale-italiana-in-PES-2020-\u00e8-risultata-campione-dEuropa.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/news\\\/la-nazionale-italiana-in-pes-2020-e-risultata-campione-deuropa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/news\\\/la-nazionale-italiana-in-pes-2020-e-risultata-campione-deuropa\\\/\",\"url\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/news\\\/la-nazionale-italiana-in-pes-2020-e-risultata-campione-deuropa\\\/\",\"name\":\"La nazionale italiana in PES 2020 \u00e8 risultata campione d'Europa - HW Legend Games\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/news\\\/la-nazionale-italiana-in-pes-2020-e-risultata-campione-deuropa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/news\\\/la-nazionale-italiana-in-pes-2020-e-risultata-campione-deuropa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/05\\\/Cop-La-nazionale-italiana-in-PES-2020-\u00e8-risultata-campione-dEuropa.jpg\",\"datePublished\":\"2020-05-25T17:50:28+00:00\",\"dateModified\":\"2020-05-25T17:51:19+00:00\",\"description\":\"Un risultato straordinario quello ottenuto dalla eNazionale TIMVISION PES, consentendo alla FIGC di conquistare il suo primo trofeo nel mondo dell'eFoot.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/news\\\/la-nazionale-italiana-in-pes-2020-e-risultata-campione-deuropa\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/news\\\/la-nazionale-italiana-in-pes-2020-e-risultata-campione-deuropa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/news\\\/la-nazionale-italiana-in-pes-2020-e-risultata-campione-deuropa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/05\\\/Cop-La-nazionale-italiana-in-PES-2020-\u00e8-risultata-campione-dEuropa.jpg\",\"contentUrl\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/05\\\/Cop-La-nazionale-italiana-in-PES-2020-\u00e8-risultata-campione-dEuropa.jpg\",\"width\":555,\"height\":410},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/news\\\/la-nazionale-italiana-in-pes-2020-e-risultata-campione-deuropa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La nazionale italiana in PES 2020 \u00e8 risultata campione d&#8217;Europa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/#website\",\"url\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/\",\"name\":\"HW Legend Games\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/#organization\",\"name\":\"HW Legend Games\",\"url\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/05\\\/Logo-Manguste-trasparente.webp\",\"contentUrl\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/05\\\/Logo-Manguste-trasparente.webp\",\"width\":700,\"height\":245,\"caption\":\"HW Legend Games\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/#\\\/schema\\\/person\\\/3ed113744596ad4689eacfe0d695fcb4\",\"name\":\"djlegend\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d482afe0f6886eac7c042c0145bd9cf53427dcba7126ebb7feadae6e1c03b1ca?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d482afe0f6886eac7c042c0145bd9cf53427dcba7126ebb7feadae6e1c03b1ca?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d482afe0f6886eac7c042c0145bd9cf53427dcba7126ebb7feadae6e1c03b1ca?s=96&d=mm&r=g\",\"caption\":\"djlegend\"},\"url\":\"https:\\\/\\\/www.hwlegend.tech\\\/games\\\/author\\\/djlegend\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La nazionale italiana in PES 2020 \u00e8 risultata campione d'Europa - HW Legend Games","description":"Un risultato straordinario quello ottenuto dalla eNazionale TIMVISION PES, consentendo alla FIGC di conquistare il suo primo trofeo nel mondo dell'eFoot.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hwlegend.tech\/games\/news\/la-nazionale-italiana-in-pes-2020-e-risultata-campione-deuropa\/","og_locale":"it_IT","og_type":"article","og_title":"La nazionale italiana in PES 2020 \u00e8 risultata campione d'Europa - HW Legend Games","og_description":"Un risultato straordinario quello ottenuto dalla eNazionale TIMVISION PES, consentendo alla FIGC di conquistare il suo primo trofeo nel mondo dell'eFoot.","og_url":"https:\/\/www.hwlegend.tech\/games\/news\/la-nazionale-italiana-in-pes-2020-e-risultata-campione-deuropa\/","og_site_name":"HW Legend Games","article_published_time":"2020-05-25T17:50:28+00:00","article_modified_time":"2020-05-25T17:51:19+00:00","og_image":[{"width":555,"height":410,"url":"https:\/\/www.hwlegend.tech\/games\/wp-content\/uploads\/sites\/2\/2020\/05\/Cop-La-nazionale-italiana-in-PES-2020-\u00e8-risultata-campione-dEuropa.jpg","type":"image\/jpeg"}],"author":"djlegend","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"djlegend","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.hwlegend.tech\/games\/news\/la-nazionale-italiana-in-pes-2020-e-risultata-campione-deuropa\/#article","isPartOf":{"@id":"https:\/\/www.hwlegend.tech\/games\/news\/la-nazionale-italiana-in-pes-2020-e-risultata-campione-deuropa\/"},"author":{"name":"djlegend","@id":"https:\/\/www.hwlegend.tech\/games\/#\/schema\/person\/3ed113744596ad4689eacfe0d695fcb4"},"headline":"La nazionale italiana in PES 2020 \u00e8 risultata campione d&#8217;Europa","datePublished":"2020-05-25T17:50:28+00:00","dateModified":"2020-05-25T17:51:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.hwlegend.tech\/games\/news\/la-nazionale-italiana-in-pes-2020-e-risultata-campione-deuropa\/"},"wordCount":525,"commentCount":0,"publisher":{"@id":"https:\/\/www.hwlegend.tech\/games\/#organization"},"image":{"@id":"https:\/\/www.hwlegend.tech\/games\/news\/la-nazionale-italiana-in-pes-2020-e-risultata-campione-deuropa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hwlegend.tech\/games\/wp-content\/uploads\/sites\/2\/2020\/05\/Cop-La-nazionale-italiana-in-PES-2020-\u00e8-risultata-campione-dEuropa.jpg","articleSection":["News"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.hwlegend.tech\/games\/news\/la-nazionale-italiana-in-pes-2020-e-risultata-campione-deuropa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.hwlegend.tech\/games\/news\/la-nazionale-italiana-in-pes-2020-e-risultata-campione-deuropa\/","url":"https:\/\/www.hwlegend.tech\/games\/news\/la-nazionale-italiana-in-pes-2020-e-risultata-campione-deuropa\/","name":"La nazionale italiana in PES 2020 \u00e8 risultata campione d'Europa - HW Legend Games","isPartOf":{"@id":"https:\/\/www.hwlegend.tech\/games\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hwlegend.tech\/games\/news\/la-nazionale-italiana-in-pes-2020-e-risultata-campione-deuropa\/#primaryimage"},"image":{"@id":"https:\/\/www.hwlegend.tech\/games\/news\/la-nazionale-italiana-in-pes-2020-e-risultata-campione-deuropa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hwlegend.tech\/games\/wp-content\/uploads\/sites\/2\/2020\/05\/Cop-La-nazionale-italiana-in-PES-2020-\u00e8-risultata-campione-dEuropa.jpg","datePublished":"2020-05-25T17:50:28+00:00","dateModified":"2020-05-25T17:51:19+00:00","description":"Un risultato straordinario quello ottenuto dalla eNazionale TIMVISION PES, consentendo alla FIGC di conquistare il suo primo trofeo nel mondo dell'eFoot.","breadcrumb":{"@id":"https:\/\/www.hwlegend.tech\/games\/news\/la-nazionale-italiana-in-pes-2020-e-risultata-campione-deuropa\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hwlegend.tech\/games\/news\/la-nazionale-italiana-in-pes-2020-e-risultata-campione-deuropa\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.hwlegend.tech\/games\/news\/la-nazionale-italiana-in-pes-2020-e-risultata-campione-deuropa\/#primaryimage","url":"https:\/\/www.hwlegend.tech\/games\/wp-content\/uploads\/sites\/2\/2020\/05\/Cop-La-nazionale-italiana-in-PES-2020-\u00e8-risultata-campione-dEuropa.jpg","contentUrl":"https:\/\/www.hwlegend.tech\/games\/wp-content\/uploads\/sites\/2\/2020\/05\/Cop-La-nazionale-italiana-in-PES-2020-\u00e8-risultata-campione-dEuropa.jpg","width":555,"height":410},{"@type":"BreadcrumbList","@id":"https:\/\/www.hwlegend.tech\/games\/news\/la-nazionale-italiana-in-pes-2020-e-risultata-campione-deuropa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.hwlegend.tech\/games\/"},{"@type":"ListItem","position":2,"name":"La nazionale italiana in PES 2020 \u00e8 risultata campione d&#8217;Europa"}]},{"@type":"WebSite","@id":"https:\/\/www.hwlegend.tech\/games\/#website","url":"https:\/\/www.hwlegend.tech\/games\/","name":"HW Legend Games","description":"","publisher":{"@id":"https:\/\/www.hwlegend.tech\/games\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hwlegend.tech\/games\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.hwlegend.tech\/games\/#organization","name":"HW Legend Games","url":"https:\/\/www.hwlegend.tech\/games\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.hwlegend.tech\/games\/#\/schema\/logo\/image\/","url":"https:\/\/www.hwlegend.tech\/games\/wp-content\/uploads\/sites\/2\/2025\/05\/Logo-Manguste-trasparente.webp","contentUrl":"https:\/\/www.hwlegend.tech\/games\/wp-content\/uploads\/sites\/2\/2025\/05\/Logo-Manguste-trasparente.webp","width":700,"height":245,"caption":"HW Legend Games"},"image":{"@id":"https:\/\/www.hwlegend.tech\/games\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.hwlegend.tech\/games\/#\/schema\/person\/3ed113744596ad4689eacfe0d695fcb4","name":"djlegend","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/d482afe0f6886eac7c042c0145bd9cf53427dcba7126ebb7feadae6e1c03b1ca?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d482afe0f6886eac7c042c0145bd9cf53427dcba7126ebb7feadae6e1c03b1ca?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d482afe0f6886eac7c042c0145bd9cf53427dcba7126ebb7feadae6e1c03b1ca?s=96&d=mm&r=g","caption":"djlegend"},"url":"https:\/\/www.hwlegend.tech\/games\/author\/djlegend\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hwlegend.tech\/games\/wp-json\/wp\/v2\/posts\/16327","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hwlegend.tech\/games\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hwlegend.tech\/games\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hwlegend.tech\/games\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hwlegend.tech\/games\/wp-json\/wp\/v2\/comments?post=16327"}],"version-history":[{"count":1,"href":"https:\/\/www.hwlegend.tech\/games\/wp-json\/wp\/v2\/posts\/16327\/revisions"}],"predecessor-version":[{"id":16330,"href":"https:\/\/www.hwlegend.tech\/games\/wp-json\/wp\/v2\/posts\/16327\/revisions\/16330"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hwlegend.tech\/games\/wp-json\/wp\/v2\/media\/16328"}],"wp:attachment":[{"href":"https:\/\/www.hwlegend.tech\/games\/wp-json\/wp\/v2\/media?parent=16327"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hwlegend.tech\/games\/wp-json\/wp\/v2\/categories?post=16327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}