{"id":4661,"date":"2020-05-01T11:54:39","date_gmt":"2020-05-01T09:54:39","guid":{"rendered":"https:\/\/www.hwlegend.tech\/modding\/?p=4661"},"modified":"2020-05-01T11:55:40","modified_gmt":"2020-05-01T09:55:40","slug":"gigabyte-presenta-ufficialmente-le-nuove-schede-madri-z490-aorus","status":"publish","type":"post","link":"https:\/\/www.hwlegend.tech\/modding\/news\/gigabyte-presenta-ufficialmente-le-nuove-schede-madri-z490-aorus\/","title":{"rendered":"GIGABYTE presenta ufficialmente le nuove schede madri Z490 AORUS"},"content":{"rendered":"<hr \/>\n<p><strong>GIGABYTE TECHNOLOGY Co.\u00a0Ltd<\/strong>, leader nella produzione di schede madri e schede grafiche, ha annunciato oggi le nuove schede madri <a href=\"https:\/\/www.gigabyte.com\/Motherboard\/Intel-Z490\" target=\"_blank\" rel=\"noopener noreferrer\">Z490 AORUS<\/a> che supportano i processori <strong>Intel Core di decima generazione<\/strong>.<\/p>\n<p><a href=\"https:\/\/www.hwlegend.tech\/wp-content\/uploads\/2020\/05\/GIGABYTE-presenta-ufficialmente-le-nuove-schede-madri-Z490-AORUS.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-148906\" src=\"https:\/\/www.hwlegend.tech\/wp-content\/uploads\/2020\/05\/GIGABYTE-presenta-ufficialmente-le-nuove-schede-madri-Z490-AORUS-1024x427.jpg\" alt=\"\" width=\"1024\" height=\"427\" \/><\/a><\/p>\n<p>Dotate di design di alimentazione digitale a 16 fasi e design dei dissipatori migliorato di tipo Fins-Array II, in modo che ogni fase possa fornire 90A, la linea Z490 di GIGABYTE \u00e8 equipaggiata con la migliore gestione termica e di alimentazione per ottimizzare le prestazioni di overclocking sul processore Intel Core serie K a 10 core. Le schede madri GIGABYTE Z490 AORUS utilizzano il routing Daisy Chain con un design anti-interferenza per migliorare overclocking e stabilit\u00e0 della memoria.<\/p>\n<p>Schede madri selezionate GIGABYTE Z490 AORUS offrono la migliore qualit\u00e0 audio, I\/0 ricco di funzionalit\u00e0 con shield integrato, la pi\u00f9 recente tecnologia Thermal Guard II e molto altro. Prestazioni, gestione termica e di alimentazione, comparto audio, le schede madri GIGABYTE Z490 AORUS soddisfano tutte le esigenze degli utenti che vogliono portare al massimo livello la potenza dei loro sistemi.<\/p>\n<p><a href=\"https:\/\/www.hwlegend.tech\/wp-content\/uploads\/2020\/05\/GIGABYTE-presenta-ufficialmente-le-nuove-schede-madri-Z490-AORUS-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-148912\" src=\"https:\/\/www.hwlegend.tech\/wp-content\/uploads\/2020\/05\/GIGABYTE-presenta-ufficialmente-le-nuove-schede-madri-Z490-AORUS-1.jpg\" alt=\"\" width=\"505\" height=\"631\" \/><\/a><\/p>\n<p>La decima generazione di processori Intel Core con nuova microarchitettura \u00e8 arrivata, e con essa arriva anche il socket LGA 1200, il che significa che le piattaforme pi\u00f9 datate non saranno compatibili nemmeno con update del BIOS. Il Core i9-10900K supera i processori della generazione precedente con i suoi 10 core e 20 thread, insieme a una cache da 20MB e un TDP di default di 125W.<\/p>\n<p>Con Turbo Boost Max, \u00e8 in grado di raggiungere i 5 GHz su quasi tutti i core. L&#8217;aumento del numero di core e delle frequenze di stock porter\u00e0 probabilmente a un consumo di energia pi\u00f9 elevato poich\u00e9, al fine di realizzare l&#8217;arduo compito di raggiungere i 5,3 GHz su tutti i core, potrebbe essere necessario un TDP di oltre 200 W.<\/p>\n<p>Le schede madri GIGABYTE Z490 AORUS includono un design di alimentazione digitale a 16 fasi in cui ogni fase pu\u00f2 fornire fino a 90A grazie al design Smart Power Stage, o un design di alimentazione diretta a 12 fasi abbinato a Power Stages DrMOS altamente durevoli per fornire 1440A, entrambi offrono il miglior bilanciamento dell&#8217;alimentazione.<\/p>\n<p><a href=\"https:\/\/www.hwlegend.tech\/wp-content\/uploads\/2020\/05\/GIGABYTE-presenta-ufficialmente-le-nuove-schede-madri-Z490-AORUS-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-148913\" src=\"https:\/\/www.hwlegend.tech\/wp-content\/uploads\/2020\/05\/GIGABYTE-presenta-ufficialmente-le-nuove-schede-madri-Z490-AORUS-2.jpg\" alt=\"\" width=\"498\" height=\"637\" \/><\/a><\/p>\n<p>I connettori di tipo solid-pin sulle schede madri GIGABYTE Z490 AORUS assicurano che l&#8217;erogazione di energia sia stabile, riducendo al tempo stesso il calore in eccesso durante l&#8217;overclocking per impedire fenomeni di throttling. L&#8217;aggiunta di condensatori polimerici al tantalio migliora la risposta transitoria del VRM tra carichi elevati e bassi, aumentando la stabilit\u00e0 del processore in modo che non ci si debba preoccupare di errori di overclocking causati da alimentazione instabile.<\/p>\n<p>Le schede madri GIGABYTE Z490 AORUS sono progettate con una rinnovata attenzione alla dissipazione del calore. A partire da GIGABYTE Z490 AORUS PRO la gamma implementa la tecnologia Fins-Array II, che presenta un dissipatore riprogettato che offre una superficie 3 volte superiore rispetto ai dissipatori tradizionali, con nuove alette rimodellate che consentono una dissipazione del calore superiore. La tecnologia Direct-Touch Heatpipe II \u00e8 caratterizzata da un heatpipe a contatto diretto pi\u00f9 grande da 8mm con distanza ridotta e maggiore area di contatto tra l&#8217;heatpipe e il dissipatore, per accelerare il trasferimento del calore dal VRM ai dissipatori, abbassando significativamente le temperature.<\/p>\n<p>Le schede madri GIGABYTE Z490 AORUS implementano un pad termico LAIRD 7.5W\/mK di nuova generazione, che offre una dissipazione del calore 4 volte superiore rispetto ai pad termici tradizionali e, aumentando il contatto tra VRM e pad termico, contribuisce ulteriormente alla dissipazione del calore complessiva. Con funzionalit\u00e0 e stile, il backplate posteriore in metallo aggiunge ulteriore robustezza e rigidit\u00e0 alla motherboard, mentre il rivestimento in nano-carbonio dissipa rapidamente il calore dai componenti posteriori e dal PCB.<\/p>\n<p><a href=\"https:\/\/www.hwlegend.tech\/wp-content\/uploads\/2020\/05\/GIGABYTE-presenta-ufficialmente-le-nuove-schede-madri-Z490-AORUS-3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-148914\" src=\"https:\/\/www.hwlegend.tech\/wp-content\/uploads\/2020\/05\/GIGABYTE-presenta-ufficialmente-le-nuove-schede-madri-Z490-AORUS-3.jpg\" alt=\"\" width=\"460\" height=\"631\" \/><\/a><\/p>\n<p>Oltre alla gestione energetica e termica, le schede madri GIGABYTE Z490 AORUS vantano anche un&#8217;impressionante configurazione di memoria con capacit\u00e0 di 32GB per singolo slot. Il design anti-interferenza del PCB assicura che la configurazione della memoria sia adatta alle esigenze della maggior parte degli utenti. I circuiti di memoria sono incorporati nei layer del PCB, e lo strato metallico esterno del PCB riduce le interferenze elettromagnetiche, consentendo che coloro che utilizzano la configurazione a doppio canale possano godere di prestazioni di overclock delle RAM stabili e veloci fino a DDR4 4800MHz.<\/p>\n<p>GIGABYTE Z490 AORUS XTREME presenta l&#8217;esclusivo design SMT Memory DIMM che utilizza la tecnologia di saldatura ad aderenza superficiale, in modo che i giunti di saldatura degli slot di memoria siano fissati senza problemi sul PCB riducendo le interferenze. La funzione di stabilizzazione del segnale dei condensatori polimerici al tantalio alla base degli slot di memora migliora ulteriormente la stabilit\u00e0 della scheda, soprattutto in situazioni di overclocking ad alte frequenze XMP.<\/p>\n<p>Oltre al processore e alla RAM, le unit\u00e0 di archiviazione sono alcuni dei componenti pi\u00f9 importanti del PC in relazione alle prestazioni del PC. Le schede madri della serie GIGABYTE Z490 utilizzano PCB PCIe 4.0, slot PCIe, slot M.2 e controller per la massima qualit\u00e0 di larghezza di banda. Sebbene le capacit\u00e0 di archiviazione sugli SSD M.2 NVMe continuino ad aumentare e molti di questi SSD siano a doppio lato, i dissipatori SSD M.2 sulla maggior parte delle schede madri coprono solo un lato dell&#8217;SSD, lasciando le unit\u00e0 di archiviazione vulnerabili al surriscaldamento.<\/p>\n<p><a href=\"https:\/\/www.hwlegend.tech\/wp-content\/uploads\/2020\/05\/GIGABYTE-presenta-ufficialmente-le-nuove-schede-madri-Z490-AORUS-4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-148915\" src=\"https:\/\/www.hwlegend.tech\/wp-content\/uploads\/2020\/05\/GIGABYTE-presenta-ufficialmente-le-nuove-schede-madri-Z490-AORUS-4.jpg\" alt=\"\" width=\"478\" height=\"643\" \/><\/a><\/p>\n<p>Per ovviare a questo potenziale collo di bottiglia, schede madri selezionate GIGABYTE Z490 AORUS sono fornite con Thermal Guard II. Con esclusivi miglioramenti rispetto al dissipatore di calore M.2 della generazione precedente, il nuovo design brevettato garantisce che entrambi i lati dell&#8217;SSD M.2 siano adeguatamente raffreddati per impedire il thermal throttling durante il funzionamento.<\/p>\n<p>Schede madri selezionate Z490 AORUS sono dotate di shield I\/O flessibile brevettato, che aggiunge un tocco gradevole all&#8217;estetica generale e soprattutto consente un pi\u00f9 facile allineamento tra la scheda e il case. Lo shield offre una protezione aggiuntiva al ricco pannello posteriore che include slot USB 3.1 Gen2, Ethernet 2.5G e 10G, prese audio e interfaccia di espansione Thunderbolt 3. L&#8217;aggiunta dei pulsanti QFLASH e Clear CMOS rende molto pi\u00f9 semplice e conveniente per gli utenti risolvere i problemi dei propri sistemi o aggiornare il BIOS senza installare un processore.<\/p>\n<p><a href=\"https:\/\/www.hwlegend.tech\/wp-content\/uploads\/2020\/05\/GIGABYTE-presenta-ufficialmente-le-nuove-schede-madri-Z490-AORUS-5.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-148916\" src=\"https:\/\/www.hwlegend.tech\/wp-content\/uploads\/2020\/05\/GIGABYTE-presenta-ufficialmente-le-nuove-schede-madri-Z490-AORUS-5.jpg\" alt=\"\" width=\"468\" height=\"644\" \/><\/a><\/p>\n<p>La scheda Ethernet Intel da 2,5 Gbps della scheda offre una connettivit\u00e0 ultraveloce che \u00e8 2,5 pi\u00f9 veloce di Ethernet Gigabit. Inoltre, la motherboard implementa una scheda di rete Intel WiFi 6 802.11ax e un&#8217;antenna intelligente WiFi AORUS per offrire una velocit\u00e0 di trasmissione fino a 2,4 Gbps. La configurazione Ethernet e WiFi offre agli utenti una configurazione flessibile con connettivit\u00e0 Internet stabile e ultraveloce.<\/p>\n<p>Quando si tratta di audio, GIGABYTE \u00e8 sempre al top. Modelli selezionati di schede madri Z490 GIGABYTE AORUS utilizzano ALC 1220-VB audio engine insieme ai condensatori WIMA FKP2 di qualit\u00e0 professionale, per fornire audio ad alta fedelt\u00e0. L&#8217;esclusivo design audio GIGABYTE integra ESS SABRE DAC, spesso utilizzato in dispositivi audio professionali, cos\u00ec come DTS\uff1aX\u00a0Ultra per offrire audio ad alta fedelt\u00e0, per l&#8217;esperienza sonora pi\u00f9 coinvolgente sia che si tratti di giochi o di guardare film e ascoltare musica.<\/p>\n<p>La top di gamma Z490 AORUS XTREME introduce ESSential USB DAC tramite l&#8217;interfaccia USB Type-C e un convertitore integrato ESS SABRE HiFi ES9280C PRO, che pu\u00f2 liberare un jack audio e utilizzare uno slot USB convertito in un&#8217;uscita audio da 3,5 mm. ESSential USB DAC pu\u00f2 essere utilizzato anche con telefoni o tablet Android con interfacce USB Type-C per offrire un&#8217;esperienza audio pi\u00f9 coinvolgente.<\/p>\n<p><a href=\"https:\/\/www.hwlegend.tech\/wp-content\/uploads\/2020\/05\/GIGABYTE-presenta-ufficialmente-le-nuove-schede-madri-Z490-AORUS-6.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-148917\" src=\"https:\/\/www.hwlegend.tech\/wp-content\/uploads\/2020\/05\/GIGABYTE-presenta-ufficialmente-le-nuove-schede-madri-Z490-AORUS-6.jpg\" alt=\"\" width=\"447\" height=\"620\" \/><\/a><\/p>\n<p>Le schede madri GIGABYTE Z490 AORUS ripresentano le tecnologie preferite dai fan, come RGB Fusion con supporto per le strisce di illuminazione digitale, la tecnologia Smart Fan 5, USB TurboCharger per la ricarica ultraveloce sui telefoni e altre tecnologie. Il BIOS GIGABYTE \u00e8 stato completamente rinnovato con una nuova interfaccia grafica che visualizza le informazioni chiave su velocit\u00e0 di clock, memoria, dispositivi di archiviazione, stato e impostazioni delle ventole, e altre importanti informazioni hardware in modo pi\u00f9 intuitivo e user-friendly. La tecnologia Q-Flash Plus consente di mantenere il BIOS del sistema in un&#8217;unit\u00e0 flash USB senza installare CPU, RAM, GPU e altre periferiche.<\/p>\n<p>Con la tecnologia GIGABYTE Ultra-Durable, condensatori solidi, design di alimentazione digitale con controllo intelligente delle ventole, queste nuove schede madri offrono al tempo stesso efficienza energetica, le migliori performance e durata del prodotto. Le schede madri gaming GIGABYTE Z490 AORUS rappresentano la prossima generazione della tecnologia PC.<\/p>\n<hr \/>\n<p style=\"text-align: center\"><strong>HW Legend Modding Staff<\/strong><\/p>\n<hr \/>\n<div class=\"gsp_post_data\" \r\n\t            data-post_type=\"post\" \r\n\t            data-cat=\"news\" \r\n\t            data-modified=\"120\"\r\n\t            data-created=\"1588334079\"\r\n\t            data-title=\"GIGABYTE presenta ufficialmente le nuove schede madri Z490 AORUS\" \r\n\t            data-home=\"https:\/\/www.hwlegend.tech\/modding\"><\/div>","protected":false},"excerpt":{"rendered":"<p>GIGABYTE TECHNOLOGY Co.\u00a0Ltd, leader nella produzione di schede madri e schede grafiche, ha annunciato oggi le nuove schede madri Z490 AORUS che supportano i processori Intel Core di decima generazione. Dotate di design di alimentazione digitale a 16 fasi e design dei dissipatori migliorato di tipo Fins-Array II, in modo che ogni fase possa fornire [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4662,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"class_list":["post-4661","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>GIGABYTE presenta ufficialmente le nuove schede madri Z490 AORUS - HW Legend Modding<\/title>\n<meta name=\"description\" content=\"GIGABYTE TECHNOLOGY Co. Ltd, ha annunciato le nuove schede madri Z490 AORUS che supportano i processori Intel Core di decima generazione.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hwlegend.tech\/news\/varie\/gigabyte-presenta-ufficialmente-le-nuove-schede-madri-z490-aorus\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GIGABYTE presenta ufficialmente le nuove schede madri Z490 AORUS - HW Legend Modding\" \/>\n<meta property=\"og:description\" content=\"GIGABYTE TECHNOLOGY Co. Ltd, ha annunciato le nuove schede madri Z490 AORUS che supportano i processori Intel Core di decima generazione.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hwlegend.tech\/news\/varie\/gigabyte-presenta-ufficialmente-le-nuove-schede-madri-z490-aorus\/\" \/>\n<meta property=\"og:site_name\" content=\"HW Legend Modding\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-01T09:54:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-01T09:55:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hwlegend.tech\/modding\/wp-content\/uploads\/sites\/3\/2020\/05\/Cop-GIGABYTE-presenta-ufficialmente-le-nuove-schede-madri-Z490-AORUS.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"555\" \/>\n\t<meta property=\"og:image:height\" content=\"410\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"djlegend\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"djlegend\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/news\\\/varie\\\/gigabyte-presenta-ufficialmente-le-nuove-schede-madri-z490-aorus\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/modding\\\/news\\\/gigabyte-presenta-ufficialmente-le-nuove-schede-madri-z490-aorus\\\/\"},\"author\":{\"name\":\"djlegend\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/modding\\\/#\\\/schema\\\/person\\\/3ed113744596ad4689eacfe0d695fcb4\"},\"headline\":\"GIGABYTE presenta ufficialmente le nuove schede madri Z490 AORUS\",\"datePublished\":\"2020-05-01T09:54:39+00:00\",\"dateModified\":\"2020-05-01T09:55:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/modding\\\/news\\\/gigabyte-presenta-ufficialmente-le-nuove-schede-madri-z490-aorus\\\/\"},\"wordCount\":1367,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/modding\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/news\\\/varie\\\/gigabyte-presenta-ufficialmente-le-nuove-schede-madri-z490-aorus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hwlegend.tech\\\/modding\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/05\\\/Cop-GIGABYTE-presenta-ufficialmente-le-nuove-schede-madri-Z490-AORUS.jpg\",\"keywords\":[\"Comet Lake-S\",\"GIGABYTE TECHNOLOGY Co. Ltd\",\"GIGABYTE Z490 AORUS\",\"GIGABYTE Z490 AORUS ELITE\",\"GIGABYTE Z490 AORUS ELITE AC\",\"GIGABYTE Z490 AORUS MASTER\",\"GIGABYTE Z490 AORUS PRO AX\",\"GIGABYTE Z490 AORUS ULTRA\",\"GIGABYTE Z490 AORUS ULTRA G2\",\"GIGABYTE Z490 AORUS XTREME\",\"GIGABYTE Z490 AORUS XTREME WATERFORCE\",\"GIGABYTE Z490i AORUS ULTRA\",\"Intel Comet Lake-S\",\"Intel Core di decima generazione\",\"Z490 AORUS\",\"Z490 AORUS ELITE\",\"Z490 AORUS ELITE AC\",\"Z490 AORUS MASTER\",\"Z490 AORUS PRO AX\",\"Z490 AORUS ULTRA\",\"Z490 AORUS ULTRA G2\",\"Z490 AORUS XTREME\",\"Z490 AORUS XTREME WATERFORCE\",\"Z490i AORUS ULTRA\"],\"articleSection\":[\"News\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.hwlegend.tech\\\/news\\\/varie\\\/gigabyte-presenta-ufficialmente-le-nuove-schede-madri-z490-aorus\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/modding\\\/news\\\/gigabyte-presenta-ufficialmente-le-nuove-schede-madri-z490-aorus\\\/\",\"url\":\"https:\\\/\\\/www.hwlegend.tech\\\/news\\\/varie\\\/gigabyte-presenta-ufficialmente-le-nuove-schede-madri-z490-aorus\\\/\",\"name\":\"GIGABYTE presenta ufficialmente le nuove schede madri Z490 AORUS - HW Legend Modding\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/modding\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/news\\\/varie\\\/gigabyte-presenta-ufficialmente-le-nuove-schede-madri-z490-aorus\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/news\\\/varie\\\/gigabyte-presenta-ufficialmente-le-nuove-schede-madri-z490-aorus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hwlegend.tech\\\/modding\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/05\\\/Cop-GIGABYTE-presenta-ufficialmente-le-nuove-schede-madri-Z490-AORUS.jpg\",\"datePublished\":\"2020-05-01T09:54:39+00:00\",\"dateModified\":\"2020-05-01T09:55:40+00:00\",\"description\":\"GIGABYTE TECHNOLOGY Co. Ltd, ha annunciato le nuove schede madri Z490 AORUS che supportano i processori Intel Core di decima generazione.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/news\\\/varie\\\/gigabyte-presenta-ufficialmente-le-nuove-schede-madri-z490-aorus\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hwlegend.tech\\\/news\\\/varie\\\/gigabyte-presenta-ufficialmente-le-nuove-schede-madri-z490-aorus\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/news\\\/varie\\\/gigabyte-presenta-ufficialmente-le-nuove-schede-madri-z490-aorus\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.hwlegend.tech\\\/modding\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/05\\\/Cop-GIGABYTE-presenta-ufficialmente-le-nuove-schede-madri-Z490-AORUS.jpg\",\"contentUrl\":\"https:\\\/\\\/www.hwlegend.tech\\\/modding\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/05\\\/Cop-GIGABYTE-presenta-ufficialmente-le-nuove-schede-madri-Z490-AORUS.jpg\",\"width\":555,\"height\":410},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/news\\\/varie\\\/gigabyte-presenta-ufficialmente-le-nuove-schede-madri-z490-aorus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.hwlegend.tech\\\/modding\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"GIGABYTE presenta ufficialmente le nuove schede madri Z490 AORUS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/modding\\\/#website\",\"url\":\"https:\\\/\\\/www.hwlegend.tech\\\/modding\\\/\",\"name\":\"HW Legend Modding\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/modding\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hwlegend.tech\\\/modding\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/modding\\\/#organization\",\"name\":\"HW Legend Modding\",\"url\":\"https:\\\/\\\/www.hwlegend.tech\\\/modding\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/modding\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.hwlegend.tech\\\/modding\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/05\\\/Logo-Modding-trasparente.webp\",\"contentUrl\":\"https:\\\/\\\/www.hwlegend.tech\\\/modding\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/05\\\/Logo-Modding-trasparente.webp\",\"width\":700,\"height\":245,\"caption\":\"HW Legend Modding\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/modding\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/modding\\\/#\\\/schema\\\/person\\\/3ed113744596ad4689eacfe0d695fcb4\",\"name\":\"djlegend\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d482afe0f6886eac7c042c0145bd9cf53427dcba7126ebb7feadae6e1c03b1ca?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d482afe0f6886eac7c042c0145bd9cf53427dcba7126ebb7feadae6e1c03b1ca?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d482afe0f6886eac7c042c0145bd9cf53427dcba7126ebb7feadae6e1c03b1ca?s=96&d=mm&r=g\",\"caption\":\"djlegend\"},\"url\":\"https:\\\/\\\/www.hwlegend.tech\\\/modding\\\/author\\\/djlegend\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"GIGABYTE presenta ufficialmente le nuove schede madri Z490 AORUS - HW Legend Modding","description":"GIGABYTE TECHNOLOGY Co. Ltd, ha annunciato le nuove schede madri Z490 AORUS che supportano i processori Intel Core di decima generazione.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hwlegend.tech\/news\/varie\/gigabyte-presenta-ufficialmente-le-nuove-schede-madri-z490-aorus\/","og_locale":"it_IT","og_type":"article","og_title":"GIGABYTE presenta ufficialmente le nuove schede madri Z490 AORUS - HW Legend Modding","og_description":"GIGABYTE TECHNOLOGY Co. Ltd, ha annunciato le nuove schede madri Z490 AORUS che supportano i processori Intel Core di decima generazione.","og_url":"https:\/\/www.hwlegend.tech\/news\/varie\/gigabyte-presenta-ufficialmente-le-nuove-schede-madri-z490-aorus\/","og_site_name":"HW Legend Modding","article_published_time":"2020-05-01T09:54:39+00:00","article_modified_time":"2020-05-01T09:55:40+00:00","og_image":[{"width":555,"height":410,"url":"https:\/\/www.hwlegend.tech\/modding\/wp-content\/uploads\/sites\/3\/2020\/05\/Cop-GIGABYTE-presenta-ufficialmente-le-nuove-schede-madri-Z490-AORUS.jpg","type":"image\/jpeg"}],"author":"djlegend","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"djlegend","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.hwlegend.tech\/news\/varie\/gigabyte-presenta-ufficialmente-le-nuove-schede-madri-z490-aorus\/#article","isPartOf":{"@id":"https:\/\/www.hwlegend.tech\/modding\/news\/gigabyte-presenta-ufficialmente-le-nuove-schede-madri-z490-aorus\/"},"author":{"name":"djlegend","@id":"https:\/\/www.hwlegend.tech\/modding\/#\/schema\/person\/3ed113744596ad4689eacfe0d695fcb4"},"headline":"GIGABYTE presenta ufficialmente le nuove schede madri Z490 AORUS","datePublished":"2020-05-01T09:54:39+00:00","dateModified":"2020-05-01T09:55:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.hwlegend.tech\/modding\/news\/gigabyte-presenta-ufficialmente-le-nuove-schede-madri-z490-aorus\/"},"wordCount":1367,"commentCount":0,"publisher":{"@id":"https:\/\/www.hwlegend.tech\/modding\/#organization"},"image":{"@id":"https:\/\/www.hwlegend.tech\/news\/varie\/gigabyte-presenta-ufficialmente-le-nuove-schede-madri-z490-aorus\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hwlegend.tech\/modding\/wp-content\/uploads\/sites\/3\/2020\/05\/Cop-GIGABYTE-presenta-ufficialmente-le-nuove-schede-madri-Z490-AORUS.jpg","keywords":["Comet Lake-S","GIGABYTE TECHNOLOGY Co. Ltd","GIGABYTE Z490 AORUS","GIGABYTE Z490 AORUS ELITE","GIGABYTE Z490 AORUS ELITE AC","GIGABYTE Z490 AORUS MASTER","GIGABYTE Z490 AORUS PRO AX","GIGABYTE Z490 AORUS ULTRA","GIGABYTE Z490 AORUS ULTRA G2","GIGABYTE Z490 AORUS XTREME","GIGABYTE Z490 AORUS XTREME WATERFORCE","GIGABYTE Z490i AORUS ULTRA","Intel Comet Lake-S","Intel Core di decima generazione","Z490 AORUS","Z490 AORUS ELITE","Z490 AORUS ELITE AC","Z490 AORUS MASTER","Z490 AORUS PRO AX","Z490 AORUS ULTRA","Z490 AORUS ULTRA G2","Z490 AORUS XTREME","Z490 AORUS XTREME WATERFORCE","Z490i AORUS ULTRA"],"articleSection":["News"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.hwlegend.tech\/news\/varie\/gigabyte-presenta-ufficialmente-le-nuove-schede-madri-z490-aorus\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.hwlegend.tech\/modding\/news\/gigabyte-presenta-ufficialmente-le-nuove-schede-madri-z490-aorus\/","url":"https:\/\/www.hwlegend.tech\/news\/varie\/gigabyte-presenta-ufficialmente-le-nuove-schede-madri-z490-aorus\/","name":"GIGABYTE presenta ufficialmente le nuove schede madri Z490 AORUS - HW Legend Modding","isPartOf":{"@id":"https:\/\/www.hwlegend.tech\/modding\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hwlegend.tech\/news\/varie\/gigabyte-presenta-ufficialmente-le-nuove-schede-madri-z490-aorus\/#primaryimage"},"image":{"@id":"https:\/\/www.hwlegend.tech\/news\/varie\/gigabyte-presenta-ufficialmente-le-nuove-schede-madri-z490-aorus\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hwlegend.tech\/modding\/wp-content\/uploads\/sites\/3\/2020\/05\/Cop-GIGABYTE-presenta-ufficialmente-le-nuove-schede-madri-Z490-AORUS.jpg","datePublished":"2020-05-01T09:54:39+00:00","dateModified":"2020-05-01T09:55:40+00:00","description":"GIGABYTE TECHNOLOGY Co. Ltd, ha annunciato le nuove schede madri Z490 AORUS che supportano i processori Intel Core di decima generazione.","breadcrumb":{"@id":"https:\/\/www.hwlegend.tech\/news\/varie\/gigabyte-presenta-ufficialmente-le-nuove-schede-madri-z490-aorus\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hwlegend.tech\/news\/varie\/gigabyte-presenta-ufficialmente-le-nuove-schede-madri-z490-aorus\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.hwlegend.tech\/news\/varie\/gigabyte-presenta-ufficialmente-le-nuove-schede-madri-z490-aorus\/#primaryimage","url":"https:\/\/www.hwlegend.tech\/modding\/wp-content\/uploads\/sites\/3\/2020\/05\/Cop-GIGABYTE-presenta-ufficialmente-le-nuove-schede-madri-Z490-AORUS.jpg","contentUrl":"https:\/\/www.hwlegend.tech\/modding\/wp-content\/uploads\/sites\/3\/2020\/05\/Cop-GIGABYTE-presenta-ufficialmente-le-nuove-schede-madri-Z490-AORUS.jpg","width":555,"height":410},{"@type":"BreadcrumbList","@id":"https:\/\/www.hwlegend.tech\/news\/varie\/gigabyte-presenta-ufficialmente-le-nuove-schede-madri-z490-aorus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.hwlegend.tech\/modding\/"},{"@type":"ListItem","position":2,"name":"GIGABYTE presenta ufficialmente le nuove schede madri Z490 AORUS"}]},{"@type":"WebSite","@id":"https:\/\/www.hwlegend.tech\/modding\/#website","url":"https:\/\/www.hwlegend.tech\/modding\/","name":"HW Legend Modding","description":"","publisher":{"@id":"https:\/\/www.hwlegend.tech\/modding\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hwlegend.tech\/modding\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.hwlegend.tech\/modding\/#organization","name":"HW Legend Modding","url":"https:\/\/www.hwlegend.tech\/modding\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.hwlegend.tech\/modding\/#\/schema\/logo\/image\/","url":"https:\/\/www.hwlegend.tech\/modding\/wp-content\/uploads\/sites\/3\/2025\/05\/Logo-Modding-trasparente.webp","contentUrl":"https:\/\/www.hwlegend.tech\/modding\/wp-content\/uploads\/sites\/3\/2025\/05\/Logo-Modding-trasparente.webp","width":700,"height":245,"caption":"HW Legend Modding"},"image":{"@id":"https:\/\/www.hwlegend.tech\/modding\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.hwlegend.tech\/modding\/#\/schema\/person\/3ed113744596ad4689eacfe0d695fcb4","name":"djlegend","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/d482afe0f6886eac7c042c0145bd9cf53427dcba7126ebb7feadae6e1c03b1ca?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d482afe0f6886eac7c042c0145bd9cf53427dcba7126ebb7feadae6e1c03b1ca?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d482afe0f6886eac7c042c0145bd9cf53427dcba7126ebb7feadae6e1c03b1ca?s=96&d=mm&r=g","caption":"djlegend"},"url":"https:\/\/www.hwlegend.tech\/modding\/author\/djlegend\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hwlegend.tech\/modding\/wp-json\/wp\/v2\/posts\/4661","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hwlegend.tech\/modding\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hwlegend.tech\/modding\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hwlegend.tech\/modding\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hwlegend.tech\/modding\/wp-json\/wp\/v2\/comments?post=4661"}],"version-history":[{"count":2,"href":"https:\/\/www.hwlegend.tech\/modding\/wp-json\/wp\/v2\/posts\/4661\/revisions"}],"predecessor-version":[{"id":4665,"href":"https:\/\/www.hwlegend.tech\/modding\/wp-json\/wp\/v2\/posts\/4661\/revisions\/4665"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hwlegend.tech\/modding\/wp-json\/wp\/v2\/media\/4662"}],"wp:attachment":[{"href":"https:\/\/www.hwlegend.tech\/modding\/wp-json\/wp\/v2\/media?parent=4661"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hwlegend.tech\/modding\/wp-json\/wp\/v2\/categories?post=4661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}