{"id":1145,"date":"2019-10-09T21:11:19","date_gmt":"2019-10-09T19:11:19","guid":{"rendered":"https:\/\/www.hwlegend.tech\/overclock\/?p=1145"},"modified":"2019-10-09T22:16:43","modified_gmt":"2019-10-09T20:16:43","slug":"intel-vuole-raggiungere-i-60-fps-in-fhd-nei-giochi-esports-con-le-gpu-integrate-intel-12a-gen","status":"publish","type":"post","link":"https:\/\/www.hwlegend.tech\/overclock\/varie\/news\/intel-vuole-raggiungere-i-60-fps-in-fhd-nei-giochi-esports-con-le-gpu-integrate-intel-12a-gen\/","title":{"rendered":"Intel vuole raggiungere i 60 FPS in FHD nei giochi eSports con le GPU integrate Intel 12a gen"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-1149\" src=\"https:\/\/www.hwlegend.tech\/overclock\/wp-content\/uploads\/sites\/4\/2019\/10\/2000px-Intel-logo.svg_-1-1-1-1-1-1-1-1-1-1-2-1-1-1-1-1-1-1-1-1.png\" alt=\"\" width=\"107\" height=\"71\" \/>A <a href=\"https:\/\/wccftech.com\/intel-xe-gpu-architecture-2x-performance-ray-tracing-support\/\" target=\"_blank\" rel=\"noopener noreferrer\"><em><strong><span style=\"color: #0000ff\">quanto sembra<\/span><\/strong><\/em><\/a>, le prossime schede video integrate Intel Gen 12 potrebbero apportare un deciso salto prestazionale rispetto alle attuali soluzioni Gen 11. Durante il recente Developer Conference di Tokyo, Intel ha affermato la volont\u00e0 di voler raggiungere i 60 FPS in FHD nei giochi eSports con le GPU integrate 12a gen.<\/p>\n<hr \/>\n<p>Intel durante l&#8217;evento inoltre ha svelato le prestazioni delle attuali GPU integrate Gen 11 presenti nei processori Core 10a gen Ice Lake. I benchmark mostrano come le iGPU Gen 11 rispetto alla precedente Gen 9.5 siano decisamente pi\u00f9 prestanti ma non ancora in grado di garantire i 60 fps a 1080p con tutti i giochi eSports pi\u00f9 famosi.<\/p>\n<p><a href=\"https:\/\/www.hwlegend.tech\/wp-content\/uploads\/2019\/10\/Intel-vuole-raggiungere-i-60-FPS-in-FHD-nei-giochi-eSports-con-le-GPU-integrate-Intel-12a-gen.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-138911\" src=\"https:\/\/www.hwlegend.tech\/wp-content\/uploads\/2019\/10\/Intel-vuole-raggiungere-i-60-FPS-in-FHD-nei-giochi-eSports-con-le-GPU-integrate-Intel-12a-gen.png\" alt=\"\" width=\"1000\" height=\"664\" \/><\/a><\/p>\n<p>Kenichiro Yasu di Intel ha dichiarato che le prossime GPU integrate Intel Xe Gen 12 che saranno integrate con i processori Tiger Lake saranno in grado di raddoppiare le prestazioni rispetto alle attuali Iris Plus Gen 11, in modo tale da poter raggiungere i 60 FPS stabili con risoluzione Full-HD su tutti i pi\u00f9 importanti giohi eSports presenti ad oggi.<\/p>\n<p><a href=\"https:\/\/www.hwlegend.tech\/wp-content\/uploads\/2019\/10\/Intel-vuole-raggiungere-i-60-FPS-in-FHD-nei-giochi-eSports-con-le-GPU-integrate-Intel-12a-gen-1a.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-138914\" src=\"https:\/\/www.hwlegend.tech\/wp-content\/uploads\/2019\/10\/Intel-vuole-raggiungere-i-60-FPS-in-FHD-nei-giochi-eSports-con-le-GPU-integrate-Intel-12a-gen-1a-1024x640.jpg\" alt=\"\" width=\"1024\" height=\"640\" \/><\/a><\/p>\n<p>Le soluzioni Tiger Lake mobile con grafica Gen 12 arriveranno nel 2020, l&#8217;anno che potrebbe inoltre vedere il debutto della prima scheda grafica dedicata Intel con architettura Xe con supporto hardware per il Ray-Tracing. Non ci resta che attendere maggiori sviluppi sulla vicenda.<\/p>\n<hr \/>\n<p style=\"text-align: center\"><strong>HW Legend Overclock Staff<\/strong><\/p>\n<div class=\"gsp_post_data\" \r\n\t            data-post_type=\"post\" \r\n\t            data-cat=\"news\" \r\n\t            data-modified=\"120\"\r\n\t            data-created=\"1570655479\"\r\n\t            data-title=\"Intel vuole raggiungere i 60 FPS in FHD nei giochi eSports con le GPU integrate Intel 12a gen\" \r\n\t            data-home=\"https:\/\/www.hwlegend.tech\/overclock\"><\/div>","protected":false},"excerpt":{"rendered":"<p>A quanto sembra, le prossime schede video integrate Intel Gen 12 potrebbero apportare un deciso salto prestazionale rispetto alle attuali soluzioni Gen 11. Durante il recente Developer Conference di Tokyo, Intel ha affermato la volont\u00e0 di voler raggiungere i 60 FPS in FHD nei giochi eSports con le GPU integrate 12a gen. Intel durante l&#8217;evento [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1158,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"class_list":["post-1145","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Intel vuole raggiungere i 60 FPS in FHD nei giochi eSports con le GPU integrate Intel 12a gen - HW Legend Overclock<\/title>\n<meta name=\"description\" content=\"A quanto sembra, le schede video integrate Intel Gen 12 potrebbero apportare un deciso salto prestazionale rispetto alle attuali soluzioni Gen 11.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hwlegend.tech\/news\/hardware\/intel-vuole-raggiungere-i-60-fps-in-fhd-nei-giochi-esports-con-le-gpu-integrate-intel-12a-gen\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Intel vuole raggiungere i 60 FPS in FHD nei giochi eSports con le GPU integrate Intel 12a gen - HW Legend Overclock\" \/>\n<meta property=\"og:description\" content=\"A quanto sembra, le schede video integrate Intel Gen 12 potrebbero apportare un deciso salto prestazionale rispetto alle attuali soluzioni Gen 11.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hwlegend.tech\/news\/hardware\/intel-vuole-raggiungere-i-60-fps-in-fhd-nei-giochi-esports-con-le-gpu-integrate-intel-12a-gen\/\" \/>\n<meta property=\"og:site_name\" content=\"HW Legend Overclock\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-09T19:11:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-10-09T20:16:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hwlegend.tech\/overclock\/wp-content\/uploads\/sites\/4\/2019\/10\/Cop-Intel-vuole-raggiungere-i-60-FPS-in-FHD-nei-giochi-eSports-con-le-GPU-integrate-Intel-12a-gen.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"555\" \/>\n\t<meta property=\"og:image:height\" content=\"410\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"djlegend\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"djlegend\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/news\\\/hardware\\\/intel-vuole-raggiungere-i-60-fps-in-fhd-nei-giochi-esports-con-le-gpu-integrate-intel-12a-gen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/varie\\\/news\\\/intel-vuole-raggiungere-i-60-fps-in-fhd-nei-giochi-esports-con-le-gpu-integrate-intel-12a-gen\\\/\"},\"author\":{\"name\":\"djlegend\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/#\\\/schema\\\/person\\\/3ed113744596ad4689eacfe0d695fcb4\"},\"headline\":\"Intel vuole raggiungere i 60 FPS in FHD nei giochi eSports con le GPU integrate Intel 12a gen\",\"datePublished\":\"2019-10-09T19:11:19+00:00\",\"dateModified\":\"2019-10-09T20:16:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/varie\\\/news\\\/intel-vuole-raggiungere-i-60-fps-in-fhd-nei-giochi-esports-con-le-gpu-integrate-intel-12a-gen\\\/\"},\"wordCount\":224,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/news\\\/hardware\\\/intel-vuole-raggiungere-i-60-fps-in-fhd-nei-giochi-esports-con-le-gpu-integrate-intel-12a-gen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2019\\\/10\\\/Cop-Intel-vuole-raggiungere-i-60-FPS-in-FHD-nei-giochi-eSports-con-le-GPU-integrate-Intel-12a-gen.jpg\",\"keywords\":[\"60 FPS\",\"architettura Xe\",\"FHD\",\"giochi eSports\",\"GPU integrate\",\"GPU integrate Intel Xe Gen 12\",\"Intel\",\"Intel 12a gen\",\"Kenichiro Yasu\",\"ray-tracing\",\"Tiger Lake\",\"vuole raggiungere\"],\"articleSection\":[\"News\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.hwlegend.tech\\\/news\\\/hardware\\\/intel-vuole-raggiungere-i-60-fps-in-fhd-nei-giochi-esports-con-le-gpu-integrate-intel-12a-gen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/varie\\\/news\\\/intel-vuole-raggiungere-i-60-fps-in-fhd-nei-giochi-esports-con-le-gpu-integrate-intel-12a-gen\\\/\",\"url\":\"https:\\\/\\\/www.hwlegend.tech\\\/news\\\/hardware\\\/intel-vuole-raggiungere-i-60-fps-in-fhd-nei-giochi-esports-con-le-gpu-integrate-intel-12a-gen\\\/\",\"name\":\"Intel vuole raggiungere i 60 FPS in FHD nei giochi eSports con le GPU integrate Intel 12a gen - HW Legend Overclock\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/news\\\/hardware\\\/intel-vuole-raggiungere-i-60-fps-in-fhd-nei-giochi-esports-con-le-gpu-integrate-intel-12a-gen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/news\\\/hardware\\\/intel-vuole-raggiungere-i-60-fps-in-fhd-nei-giochi-esports-con-le-gpu-integrate-intel-12a-gen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2019\\\/10\\\/Cop-Intel-vuole-raggiungere-i-60-FPS-in-FHD-nei-giochi-eSports-con-le-GPU-integrate-Intel-12a-gen.jpg\",\"datePublished\":\"2019-10-09T19:11:19+00:00\",\"dateModified\":\"2019-10-09T20:16:43+00:00\",\"description\":\"A quanto sembra, le schede video integrate Intel Gen 12 potrebbero apportare un deciso salto prestazionale rispetto alle attuali soluzioni Gen 11.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/news\\\/hardware\\\/intel-vuole-raggiungere-i-60-fps-in-fhd-nei-giochi-esports-con-le-gpu-integrate-intel-12a-gen\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hwlegend.tech\\\/news\\\/hardware\\\/intel-vuole-raggiungere-i-60-fps-in-fhd-nei-giochi-esports-con-le-gpu-integrate-intel-12a-gen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/news\\\/hardware\\\/intel-vuole-raggiungere-i-60-fps-in-fhd-nei-giochi-esports-con-le-gpu-integrate-intel-12a-gen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2019\\\/10\\\/Cop-Intel-vuole-raggiungere-i-60-FPS-in-FHD-nei-giochi-eSports-con-le-GPU-integrate-Intel-12a-gen.jpg\",\"contentUrl\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2019\\\/10\\\/Cop-Intel-vuole-raggiungere-i-60-FPS-in-FHD-nei-giochi-eSports-con-le-GPU-integrate-Intel-12a-gen.jpg\",\"width\":555,\"height\":410},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/news\\\/hardware\\\/intel-vuole-raggiungere-i-60-fps-in-fhd-nei-giochi-esports-con-le-gpu-integrate-intel-12a-gen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Intel vuole raggiungere i 60 FPS in FHD nei giochi eSports con le GPU integrate Intel 12a gen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/#website\",\"url\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/\",\"name\":\"HW Legend Overclock\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/#organization\",\"name\":\"HW Legend Overclock\",\"url\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/05\\\/Logo-OC-finale-trasparente.webp\",\"contentUrl\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/05\\\/Logo-OC-finale-trasparente.webp\",\"width\":700,\"height\":245,\"caption\":\"HW Legend Overclock\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/#\\\/schema\\\/person\\\/3ed113744596ad4689eacfe0d695fcb4\",\"name\":\"djlegend\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d482afe0f6886eac7c042c0145bd9cf53427dcba7126ebb7feadae6e1c03b1ca?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d482afe0f6886eac7c042c0145bd9cf53427dcba7126ebb7feadae6e1c03b1ca?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d482afe0f6886eac7c042c0145bd9cf53427dcba7126ebb7feadae6e1c03b1ca?s=96&d=mm&r=g\",\"caption\":\"djlegend\"},\"url\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/author\\\/djlegend\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Intel vuole raggiungere i 60 FPS in FHD nei giochi eSports con le GPU integrate Intel 12a gen - HW Legend Overclock","description":"A quanto sembra, le schede video integrate Intel Gen 12 potrebbero apportare un deciso salto prestazionale rispetto alle attuali soluzioni Gen 11.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hwlegend.tech\/news\/hardware\/intel-vuole-raggiungere-i-60-fps-in-fhd-nei-giochi-esports-con-le-gpu-integrate-intel-12a-gen\/","og_locale":"it_IT","og_type":"article","og_title":"Intel vuole raggiungere i 60 FPS in FHD nei giochi eSports con le GPU integrate Intel 12a gen - HW Legend Overclock","og_description":"A quanto sembra, le schede video integrate Intel Gen 12 potrebbero apportare un deciso salto prestazionale rispetto alle attuali soluzioni Gen 11.","og_url":"https:\/\/www.hwlegend.tech\/news\/hardware\/intel-vuole-raggiungere-i-60-fps-in-fhd-nei-giochi-esports-con-le-gpu-integrate-intel-12a-gen\/","og_site_name":"HW Legend Overclock","article_published_time":"2019-10-09T19:11:19+00:00","article_modified_time":"2019-10-09T20:16:43+00:00","og_image":[{"width":555,"height":410,"url":"https:\/\/www.hwlegend.tech\/overclock\/wp-content\/uploads\/sites\/4\/2019\/10\/Cop-Intel-vuole-raggiungere-i-60-FPS-in-FHD-nei-giochi-eSports-con-le-GPU-integrate-Intel-12a-gen.jpg","type":"image\/jpeg"}],"author":"djlegend","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"djlegend","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.hwlegend.tech\/news\/hardware\/intel-vuole-raggiungere-i-60-fps-in-fhd-nei-giochi-esports-con-le-gpu-integrate-intel-12a-gen\/#article","isPartOf":{"@id":"https:\/\/www.hwlegend.tech\/overclock\/varie\/news\/intel-vuole-raggiungere-i-60-fps-in-fhd-nei-giochi-esports-con-le-gpu-integrate-intel-12a-gen\/"},"author":{"name":"djlegend","@id":"https:\/\/www.hwlegend.tech\/overclock\/#\/schema\/person\/3ed113744596ad4689eacfe0d695fcb4"},"headline":"Intel vuole raggiungere i 60 FPS in FHD nei giochi eSports con le GPU integrate Intel 12a gen","datePublished":"2019-10-09T19:11:19+00:00","dateModified":"2019-10-09T20:16:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.hwlegend.tech\/overclock\/varie\/news\/intel-vuole-raggiungere-i-60-fps-in-fhd-nei-giochi-esports-con-le-gpu-integrate-intel-12a-gen\/"},"wordCount":224,"commentCount":0,"publisher":{"@id":"https:\/\/www.hwlegend.tech\/overclock\/#organization"},"image":{"@id":"https:\/\/www.hwlegend.tech\/news\/hardware\/intel-vuole-raggiungere-i-60-fps-in-fhd-nei-giochi-esports-con-le-gpu-integrate-intel-12a-gen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hwlegend.tech\/overclock\/wp-content\/uploads\/sites\/4\/2019\/10\/Cop-Intel-vuole-raggiungere-i-60-FPS-in-FHD-nei-giochi-eSports-con-le-GPU-integrate-Intel-12a-gen.jpg","keywords":["60 FPS","architettura Xe","FHD","giochi eSports","GPU integrate","GPU integrate Intel Xe Gen 12","Intel","Intel 12a gen","Kenichiro Yasu","ray-tracing","Tiger Lake","vuole raggiungere"],"articleSection":["News"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.hwlegend.tech\/news\/hardware\/intel-vuole-raggiungere-i-60-fps-in-fhd-nei-giochi-esports-con-le-gpu-integrate-intel-12a-gen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.hwlegend.tech\/overclock\/varie\/news\/intel-vuole-raggiungere-i-60-fps-in-fhd-nei-giochi-esports-con-le-gpu-integrate-intel-12a-gen\/","url":"https:\/\/www.hwlegend.tech\/news\/hardware\/intel-vuole-raggiungere-i-60-fps-in-fhd-nei-giochi-esports-con-le-gpu-integrate-intel-12a-gen\/","name":"Intel vuole raggiungere i 60 FPS in FHD nei giochi eSports con le GPU integrate Intel 12a gen - HW Legend Overclock","isPartOf":{"@id":"https:\/\/www.hwlegend.tech\/overclock\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hwlegend.tech\/news\/hardware\/intel-vuole-raggiungere-i-60-fps-in-fhd-nei-giochi-esports-con-le-gpu-integrate-intel-12a-gen\/#primaryimage"},"image":{"@id":"https:\/\/www.hwlegend.tech\/news\/hardware\/intel-vuole-raggiungere-i-60-fps-in-fhd-nei-giochi-esports-con-le-gpu-integrate-intel-12a-gen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hwlegend.tech\/overclock\/wp-content\/uploads\/sites\/4\/2019\/10\/Cop-Intel-vuole-raggiungere-i-60-FPS-in-FHD-nei-giochi-eSports-con-le-GPU-integrate-Intel-12a-gen.jpg","datePublished":"2019-10-09T19:11:19+00:00","dateModified":"2019-10-09T20:16:43+00:00","description":"A quanto sembra, le schede video integrate Intel Gen 12 potrebbero apportare un deciso salto prestazionale rispetto alle attuali soluzioni Gen 11.","breadcrumb":{"@id":"https:\/\/www.hwlegend.tech\/news\/hardware\/intel-vuole-raggiungere-i-60-fps-in-fhd-nei-giochi-esports-con-le-gpu-integrate-intel-12a-gen\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hwlegend.tech\/news\/hardware\/intel-vuole-raggiungere-i-60-fps-in-fhd-nei-giochi-esports-con-le-gpu-integrate-intel-12a-gen\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.hwlegend.tech\/news\/hardware\/intel-vuole-raggiungere-i-60-fps-in-fhd-nei-giochi-esports-con-le-gpu-integrate-intel-12a-gen\/#primaryimage","url":"https:\/\/www.hwlegend.tech\/overclock\/wp-content\/uploads\/sites\/4\/2019\/10\/Cop-Intel-vuole-raggiungere-i-60-FPS-in-FHD-nei-giochi-eSports-con-le-GPU-integrate-Intel-12a-gen.jpg","contentUrl":"https:\/\/www.hwlegend.tech\/overclock\/wp-content\/uploads\/sites\/4\/2019\/10\/Cop-Intel-vuole-raggiungere-i-60-FPS-in-FHD-nei-giochi-eSports-con-le-GPU-integrate-Intel-12a-gen.jpg","width":555,"height":410},{"@type":"BreadcrumbList","@id":"https:\/\/www.hwlegend.tech\/news\/hardware\/intel-vuole-raggiungere-i-60-fps-in-fhd-nei-giochi-esports-con-le-gpu-integrate-intel-12a-gen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.hwlegend.tech\/overclock\/"},{"@type":"ListItem","position":2,"name":"Intel vuole raggiungere i 60 FPS in FHD nei giochi eSports con le GPU integrate Intel 12a gen"}]},{"@type":"WebSite","@id":"https:\/\/www.hwlegend.tech\/overclock\/#website","url":"https:\/\/www.hwlegend.tech\/overclock\/","name":"HW Legend Overclock","description":"","publisher":{"@id":"https:\/\/www.hwlegend.tech\/overclock\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hwlegend.tech\/overclock\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.hwlegend.tech\/overclock\/#organization","name":"HW Legend Overclock","url":"https:\/\/www.hwlegend.tech\/overclock\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.hwlegend.tech\/overclock\/#\/schema\/logo\/image\/","url":"https:\/\/www.hwlegend.tech\/overclock\/wp-content\/uploads\/sites\/4\/2025\/05\/Logo-OC-finale-trasparente.webp","contentUrl":"https:\/\/www.hwlegend.tech\/overclock\/wp-content\/uploads\/sites\/4\/2025\/05\/Logo-OC-finale-trasparente.webp","width":700,"height":245,"caption":"HW Legend Overclock"},"image":{"@id":"https:\/\/www.hwlegend.tech\/overclock\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.hwlegend.tech\/overclock\/#\/schema\/person\/3ed113744596ad4689eacfe0d695fcb4","name":"djlegend","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/d482afe0f6886eac7c042c0145bd9cf53427dcba7126ebb7feadae6e1c03b1ca?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d482afe0f6886eac7c042c0145bd9cf53427dcba7126ebb7feadae6e1c03b1ca?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d482afe0f6886eac7c042c0145bd9cf53427dcba7126ebb7feadae6e1c03b1ca?s=96&d=mm&r=g","caption":"djlegend"},"url":"https:\/\/www.hwlegend.tech\/overclock\/author\/djlegend\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hwlegend.tech\/overclock\/wp-json\/wp\/v2\/posts\/1145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hwlegend.tech\/overclock\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hwlegend.tech\/overclock\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hwlegend.tech\/overclock\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hwlegend.tech\/overclock\/wp-json\/wp\/v2\/comments?post=1145"}],"version-history":[{"count":0,"href":"https:\/\/www.hwlegend.tech\/overclock\/wp-json\/wp\/v2\/posts\/1145\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hwlegend.tech\/overclock\/wp-json\/wp\/v2\/media\/1158"}],"wp:attachment":[{"href":"https:\/\/www.hwlegend.tech\/overclock\/wp-json\/wp\/v2\/media?parent=1145"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hwlegend.tech\/overclock\/wp-json\/wp\/v2\/categories?post=1145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}