{"id":1752,"date":"2020-01-03T23:39:57","date_gmt":"2020-01-03T22:39:57","guid":{"rendered":"https:\/\/www.hwlegend.tech\/overclock\/?p=1752"},"modified":"2020-01-04T18:46:13","modified_gmt":"2020-01-04T17:46:13","slug":"svelata-la-foto-di-quella-che-potrebbe-essere-la-scheda-video-asrock-radeon-rx-5600-xt-phantom-gaming","status":"publish","type":"post","link":"https:\/\/www.hwlegend.tech\/overclock\/varie\/news\/svelata-la-foto-di-quella-che-potrebbe-essere-la-scheda-video-asrock-radeon-rx-5600-xt-phantom-gaming\/","title":{"rendered":"Svelata la foto di quella che potrebbe essere la scheda video ASRock Radeon RX 5600 XT Phantom Gaming"},"content":{"rendered":"<p>Nei <a href=\"https:\/\/www.hwlegend.tech\/news\/hardware\/svela-le-possibili-specifiche-tecniche-della-nuova-scheda-video-amd-radeon-rx-5600-xt\/\" target=\"_blank\" rel=\"noopener noreferrer\">giorni scorsi<\/a>, ASRock, sul proprio sito ufficiale, aveva erroneamente mostrato le possibili specifiche tecniche complete della <strong>Radeon RX 5600 XT<\/strong>. Recentemente l&#8217;azienda ha completato l&#8217;opera, <a href=\"https:\/\/videocardz.com\/newz\/asrock-radeon-rx-5600-xt-phantom-gaming-leaked\" target=\"_blank\" rel=\"noopener noreferrer\">andando di fatto a svelare<\/a>, quella che potrebbe essere l&#8217;immagine reale della nuova scheda video <strong>RX 5600 XT Phantom Gaming D3<\/strong>.<\/p>\n<hr \/>\n<p><a href=\"https:\/\/www.hwlegend.tech\/wp-content\/uploads\/2020\/01\/Svelata-la-foto-di-quella-che-potrebbe-essere-la-scheda-video-ASRock-Radeon-RX-5600-XT-Phantom-Gaming.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-143426\" src=\"https:\/\/www.hwlegend.tech\/wp-content\/uploads\/2020\/01\/Svelata-la-foto-di-quella-che-potrebbe-essere-la-scheda-video-ASRock-Radeon-RX-5600-XT-Phantom-Gaming-1024x576.jpg\" alt=\"\" width=\"1024\" height=\"576\" \/><\/a><\/p>\n<p>La ASRock RX 5600 XT Phantom Gaming D3 presenta un sistema di raffreddamento proprietario a tripla ventola in grado di garantire un maggior overclock. Ricordiamo che la scheda sar\u00e0 basata sulla GPU Navi 10 a 7nm con architettura RDNA, in grado di disporre di 2304 Stream Processor e 6GB di memoria GDDR6 con un bus a 192 bit. La frequenza della GPU \u00e8 impostata a 1560 MHz in modalit\u00e0 Game e offre un Boost fino 1620 MHz. L&#8217;alimentazione \u00e8 affidata a un singolo connettore PCI-E 8pin.<\/p>\n<p><a href=\"https:\/\/www.hwlegend.tech\/wp-content\/uploads\/2020\/01\/Svelata-la-foto-di-quella-che-potrebbe-essere-la-scheda-video-ASRock-Radeon-RX-5600-XT-Phantom-Gaming-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-143429\" src=\"https:\/\/www.hwlegend.tech\/wp-content\/uploads\/2020\/01\/Svelata-la-foto-di-quella-che-potrebbe-essere-la-scheda-video-ASRock-Radeon-RX-5600-XT-Phantom-Gaming-1-1024x379.jpg\" alt=\"\" width=\"1024\" height=\"379\" \/><\/a><\/p>\n<p>Esteticamente, oltre all&#8217;imponente dissipatore risulta ottima la preenza di accattivanti LED RGB. Ad oggi non sappiamo chiaramente data di rilascio e prezzo di vendita. Potremmo forse ottenere maggiori informazioni durante la nota fiera del CES 2020 di Las Vegas il prossimo 7 di gennaio.<\/p>\n<hr \/>\n<p style=\"text-align: center\"><strong>HW Legend Overclock Staff<\/strong><\/p>\n<div class=\"gsp_post_data\" \r\n\t            data-post_type=\"post\" \r\n\t            data-cat=\"news\" \r\n\t            data-modified=\"120\"\r\n\t            data-created=\"1578094797\"\r\n\t            data-title=\"Svelata la foto di quella che potrebbe essere la scheda video ASRock Radeon RX 5600 XT Phantom Gaming\" \r\n\t            data-home=\"https:\/\/www.hwlegend.tech\/overclock\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Nei giorni scorsi, ASRock, sul proprio sito ufficiale, aveva erroneamente mostrato le possibili specifiche tecniche complete della Radeon RX 5600 XT. Recentemente l&#8217;azienda ha completato l&#8217;opera, andando di fatto a svelare, quella che potrebbe essere l&#8217;immagine reale della nuova scheda video RX 5600 XT Phantom Gaming D3. La ASRock RX 5600 XT Phantom Gaming D3 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1757,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"class_list":["post-1752","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Svelata la foto di quella che potrebbe essere la scheda video ASRock Radeon RX 5600 XT Phantom Gaming - HW Legend Overclock<\/title>\n<meta name=\"description\" content=\"ASRock recentemente ha svelato quella che potrebbe essere l&#039;immagine reale della scheda video RX 5600 XT Phantom Gaming D3. Vediamo come potrebbe essere!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hwlegend.tech\/news\/hardware\/svelata-la-foto-di-quella-che-potrebbe-essere-la-scheda-video-asrock-radeon-rx-5600-xt-phantom-gaming\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Svelata la foto di quella che potrebbe essere la scheda video ASRock Radeon RX 5600 XT Phantom Gaming - HW Legend Overclock\" \/>\n<meta property=\"og:description\" content=\"ASRock recentemente ha svelato quella che potrebbe essere l&#039;immagine reale della scheda video RX 5600 XT Phantom Gaming D3. Vediamo come potrebbe essere!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hwlegend.tech\/news\/hardware\/svelata-la-foto-di-quella-che-potrebbe-essere-la-scheda-video-asrock-radeon-rx-5600-xt-phantom-gaming\/\" \/>\n<meta property=\"og:site_name\" content=\"HW Legend Overclock\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-03T22:39:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-01-04T17:46:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hwlegend.tech\/overclock\/wp-content\/uploads\/sites\/4\/2020\/01\/Cop-okok-final-RX-5600-XT-Phantom-Gaming-D3-ok.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"555\" \/>\n\t<meta property=\"og:image:height\" content=\"410\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"djlegend\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"djlegend\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/news\\\/hardware\\\/svelata-la-foto-di-quella-che-potrebbe-essere-la-scheda-video-asrock-radeon-rx-5600-xt-phantom-gaming\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/varie\\\/news\\\/svelata-la-foto-di-quella-che-potrebbe-essere-la-scheda-video-asrock-radeon-rx-5600-xt-phantom-gaming\\\/\"},\"author\":{\"name\":\"djlegend\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/#\\\/schema\\\/person\\\/3ed113744596ad4689eacfe0d695fcb4\"},\"headline\":\"Svelata la foto di quella che potrebbe essere la scheda video ASRock Radeon RX 5600 XT Phantom Gaming\",\"datePublished\":\"2020-01-03T22:39:57+00:00\",\"dateModified\":\"2020-01-04T17:46:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/varie\\\/news\\\/svelata-la-foto-di-quella-che-potrebbe-essere-la-scheda-video-asrock-radeon-rx-5600-xt-phantom-gaming\\\/\"},\"wordCount\":191,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/news\\\/hardware\\\/svelata-la-foto-di-quella-che-potrebbe-essere-la-scheda-video-asrock-radeon-rx-5600-xt-phantom-gaming\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2020\\\/01\\\/Cop-okok-final-RX-5600-XT-Phantom-Gaming-D3-ok.jpg\",\"keywords\":[\"ASRock\",\"ASRock RX 5600 XT Phantom Gaming D3\",\"CES 20220\",\"Radeon RX 5600 XT\",\"RX 5600 XT Phantom Gaming D3\"],\"articleSection\":[\"News\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.hwlegend.tech\\\/news\\\/hardware\\\/svelata-la-foto-di-quella-che-potrebbe-essere-la-scheda-video-asrock-radeon-rx-5600-xt-phantom-gaming\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/varie\\\/news\\\/svelata-la-foto-di-quella-che-potrebbe-essere-la-scheda-video-asrock-radeon-rx-5600-xt-phantom-gaming\\\/\",\"url\":\"https:\\\/\\\/www.hwlegend.tech\\\/news\\\/hardware\\\/svelata-la-foto-di-quella-che-potrebbe-essere-la-scheda-video-asrock-radeon-rx-5600-xt-phantom-gaming\\\/\",\"name\":\"Svelata la foto di quella che potrebbe essere la scheda video ASRock Radeon RX 5600 XT Phantom Gaming - HW Legend Overclock\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/news\\\/hardware\\\/svelata-la-foto-di-quella-che-potrebbe-essere-la-scheda-video-asrock-radeon-rx-5600-xt-phantom-gaming\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/news\\\/hardware\\\/svelata-la-foto-di-quella-che-potrebbe-essere-la-scheda-video-asrock-radeon-rx-5600-xt-phantom-gaming\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2020\\\/01\\\/Cop-okok-final-RX-5600-XT-Phantom-Gaming-D3-ok.jpg\",\"datePublished\":\"2020-01-03T22:39:57+00:00\",\"dateModified\":\"2020-01-04T17:46:13+00:00\",\"description\":\"ASRock recentemente ha svelato quella che potrebbe essere l'immagine reale della scheda video RX 5600 XT Phantom Gaming D3. Vediamo come potrebbe essere!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/news\\\/hardware\\\/svelata-la-foto-di-quella-che-potrebbe-essere-la-scheda-video-asrock-radeon-rx-5600-xt-phantom-gaming\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hwlegend.tech\\\/news\\\/hardware\\\/svelata-la-foto-di-quella-che-potrebbe-essere-la-scheda-video-asrock-radeon-rx-5600-xt-phantom-gaming\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/news\\\/hardware\\\/svelata-la-foto-di-quella-che-potrebbe-essere-la-scheda-video-asrock-radeon-rx-5600-xt-phantom-gaming\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2020\\\/01\\\/Cop-okok-final-RX-5600-XT-Phantom-Gaming-D3-ok.jpg\",\"contentUrl\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2020\\\/01\\\/Cop-okok-final-RX-5600-XT-Phantom-Gaming-D3-ok.jpg\",\"width\":555,\"height\":410},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/news\\\/hardware\\\/svelata-la-foto-di-quella-che-potrebbe-essere-la-scheda-video-asrock-radeon-rx-5600-xt-phantom-gaming\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Svelata la foto di quella che potrebbe essere la scheda video ASRock Radeon RX 5600 XT Phantom Gaming\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/#website\",\"url\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/\",\"name\":\"HW Legend Overclock\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/#organization\",\"name\":\"HW Legend Overclock\",\"url\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/05\\\/Logo-OC-finale-trasparente.webp\",\"contentUrl\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/05\\\/Logo-OC-finale-trasparente.webp\",\"width\":700,\"height\":245,\"caption\":\"HW Legend Overclock\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/#\\\/schema\\\/person\\\/3ed113744596ad4689eacfe0d695fcb4\",\"name\":\"djlegend\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d482afe0f6886eac7c042c0145bd9cf53427dcba7126ebb7feadae6e1c03b1ca?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d482afe0f6886eac7c042c0145bd9cf53427dcba7126ebb7feadae6e1c03b1ca?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d482afe0f6886eac7c042c0145bd9cf53427dcba7126ebb7feadae6e1c03b1ca?s=96&d=mm&r=g\",\"caption\":\"djlegend\"},\"url\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/author\\\/djlegend\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Svelata la foto di quella che potrebbe essere la scheda video ASRock Radeon RX 5600 XT Phantom Gaming - HW Legend Overclock","description":"ASRock recentemente ha svelato quella che potrebbe essere l'immagine reale della scheda video RX 5600 XT Phantom Gaming D3. Vediamo come potrebbe essere!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hwlegend.tech\/news\/hardware\/svelata-la-foto-di-quella-che-potrebbe-essere-la-scheda-video-asrock-radeon-rx-5600-xt-phantom-gaming\/","og_locale":"it_IT","og_type":"article","og_title":"Svelata la foto di quella che potrebbe essere la scheda video ASRock Radeon RX 5600 XT Phantom Gaming - HW Legend Overclock","og_description":"ASRock recentemente ha svelato quella che potrebbe essere l'immagine reale della scheda video RX 5600 XT Phantom Gaming D3. Vediamo come potrebbe essere!","og_url":"https:\/\/www.hwlegend.tech\/news\/hardware\/svelata-la-foto-di-quella-che-potrebbe-essere-la-scheda-video-asrock-radeon-rx-5600-xt-phantom-gaming\/","og_site_name":"HW Legend Overclock","article_published_time":"2020-01-03T22:39:57+00:00","article_modified_time":"2020-01-04T17:46:13+00:00","og_image":[{"width":555,"height":410,"url":"https:\/\/www.hwlegend.tech\/overclock\/wp-content\/uploads\/sites\/4\/2020\/01\/Cop-okok-final-RX-5600-XT-Phantom-Gaming-D3-ok.jpg","type":"image\/jpeg"}],"author":"djlegend","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"djlegend","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.hwlegend.tech\/news\/hardware\/svelata-la-foto-di-quella-che-potrebbe-essere-la-scheda-video-asrock-radeon-rx-5600-xt-phantom-gaming\/#article","isPartOf":{"@id":"https:\/\/www.hwlegend.tech\/overclock\/varie\/news\/svelata-la-foto-di-quella-che-potrebbe-essere-la-scheda-video-asrock-radeon-rx-5600-xt-phantom-gaming\/"},"author":{"name":"djlegend","@id":"https:\/\/www.hwlegend.tech\/overclock\/#\/schema\/person\/3ed113744596ad4689eacfe0d695fcb4"},"headline":"Svelata la foto di quella che potrebbe essere la scheda video ASRock Radeon RX 5600 XT Phantom Gaming","datePublished":"2020-01-03T22:39:57+00:00","dateModified":"2020-01-04T17:46:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.hwlegend.tech\/overclock\/varie\/news\/svelata-la-foto-di-quella-che-potrebbe-essere-la-scheda-video-asrock-radeon-rx-5600-xt-phantom-gaming\/"},"wordCount":191,"commentCount":0,"publisher":{"@id":"https:\/\/www.hwlegend.tech\/overclock\/#organization"},"image":{"@id":"https:\/\/www.hwlegend.tech\/news\/hardware\/svelata-la-foto-di-quella-che-potrebbe-essere-la-scheda-video-asrock-radeon-rx-5600-xt-phantom-gaming\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hwlegend.tech\/overclock\/wp-content\/uploads\/sites\/4\/2020\/01\/Cop-okok-final-RX-5600-XT-Phantom-Gaming-D3-ok.jpg","keywords":["ASRock","ASRock RX 5600 XT Phantom Gaming D3","CES 20220","Radeon RX 5600 XT","RX 5600 XT Phantom Gaming D3"],"articleSection":["News"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.hwlegend.tech\/news\/hardware\/svelata-la-foto-di-quella-che-potrebbe-essere-la-scheda-video-asrock-radeon-rx-5600-xt-phantom-gaming\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.hwlegend.tech\/overclock\/varie\/news\/svelata-la-foto-di-quella-che-potrebbe-essere-la-scheda-video-asrock-radeon-rx-5600-xt-phantom-gaming\/","url":"https:\/\/www.hwlegend.tech\/news\/hardware\/svelata-la-foto-di-quella-che-potrebbe-essere-la-scheda-video-asrock-radeon-rx-5600-xt-phantom-gaming\/","name":"Svelata la foto di quella che potrebbe essere la scheda video ASRock Radeon RX 5600 XT Phantom Gaming - HW Legend Overclock","isPartOf":{"@id":"https:\/\/www.hwlegend.tech\/overclock\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hwlegend.tech\/news\/hardware\/svelata-la-foto-di-quella-che-potrebbe-essere-la-scheda-video-asrock-radeon-rx-5600-xt-phantom-gaming\/#primaryimage"},"image":{"@id":"https:\/\/www.hwlegend.tech\/news\/hardware\/svelata-la-foto-di-quella-che-potrebbe-essere-la-scheda-video-asrock-radeon-rx-5600-xt-phantom-gaming\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hwlegend.tech\/overclock\/wp-content\/uploads\/sites\/4\/2020\/01\/Cop-okok-final-RX-5600-XT-Phantom-Gaming-D3-ok.jpg","datePublished":"2020-01-03T22:39:57+00:00","dateModified":"2020-01-04T17:46:13+00:00","description":"ASRock recentemente ha svelato quella che potrebbe essere l'immagine reale della scheda video RX 5600 XT Phantom Gaming D3. Vediamo come potrebbe essere!","breadcrumb":{"@id":"https:\/\/www.hwlegend.tech\/news\/hardware\/svelata-la-foto-di-quella-che-potrebbe-essere-la-scheda-video-asrock-radeon-rx-5600-xt-phantom-gaming\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hwlegend.tech\/news\/hardware\/svelata-la-foto-di-quella-che-potrebbe-essere-la-scheda-video-asrock-radeon-rx-5600-xt-phantom-gaming\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.hwlegend.tech\/news\/hardware\/svelata-la-foto-di-quella-che-potrebbe-essere-la-scheda-video-asrock-radeon-rx-5600-xt-phantom-gaming\/#primaryimage","url":"https:\/\/www.hwlegend.tech\/overclock\/wp-content\/uploads\/sites\/4\/2020\/01\/Cop-okok-final-RX-5600-XT-Phantom-Gaming-D3-ok.jpg","contentUrl":"https:\/\/www.hwlegend.tech\/overclock\/wp-content\/uploads\/sites\/4\/2020\/01\/Cop-okok-final-RX-5600-XT-Phantom-Gaming-D3-ok.jpg","width":555,"height":410},{"@type":"BreadcrumbList","@id":"https:\/\/www.hwlegend.tech\/news\/hardware\/svelata-la-foto-di-quella-che-potrebbe-essere-la-scheda-video-asrock-radeon-rx-5600-xt-phantom-gaming\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.hwlegend.tech\/overclock\/"},{"@type":"ListItem","position":2,"name":"Svelata la foto di quella che potrebbe essere la scheda video ASRock Radeon RX 5600 XT Phantom Gaming"}]},{"@type":"WebSite","@id":"https:\/\/www.hwlegend.tech\/overclock\/#website","url":"https:\/\/www.hwlegend.tech\/overclock\/","name":"HW Legend Overclock","description":"","publisher":{"@id":"https:\/\/www.hwlegend.tech\/overclock\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hwlegend.tech\/overclock\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.hwlegend.tech\/overclock\/#organization","name":"HW Legend Overclock","url":"https:\/\/www.hwlegend.tech\/overclock\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.hwlegend.tech\/overclock\/#\/schema\/logo\/image\/","url":"https:\/\/www.hwlegend.tech\/overclock\/wp-content\/uploads\/sites\/4\/2025\/05\/Logo-OC-finale-trasparente.webp","contentUrl":"https:\/\/www.hwlegend.tech\/overclock\/wp-content\/uploads\/sites\/4\/2025\/05\/Logo-OC-finale-trasparente.webp","width":700,"height":245,"caption":"HW Legend Overclock"},"image":{"@id":"https:\/\/www.hwlegend.tech\/overclock\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.hwlegend.tech\/overclock\/#\/schema\/person\/3ed113744596ad4689eacfe0d695fcb4","name":"djlegend","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/d482afe0f6886eac7c042c0145bd9cf53427dcba7126ebb7feadae6e1c03b1ca?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d482afe0f6886eac7c042c0145bd9cf53427dcba7126ebb7feadae6e1c03b1ca?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d482afe0f6886eac7c042c0145bd9cf53427dcba7126ebb7feadae6e1c03b1ca?s=96&d=mm&r=g","caption":"djlegend"},"url":"https:\/\/www.hwlegend.tech\/overclock\/author\/djlegend\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hwlegend.tech\/overclock\/wp-json\/wp\/v2\/posts\/1752","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hwlegend.tech\/overclock\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hwlegend.tech\/overclock\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hwlegend.tech\/overclock\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hwlegend.tech\/overclock\/wp-json\/wp\/v2\/comments?post=1752"}],"version-history":[{"count":2,"href":"https:\/\/www.hwlegend.tech\/overclock\/wp-json\/wp\/v2\/posts\/1752\/revisions"}],"predecessor-version":[{"id":1758,"href":"https:\/\/www.hwlegend.tech\/overclock\/wp-json\/wp\/v2\/posts\/1752\/revisions\/1758"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hwlegend.tech\/overclock\/wp-json\/wp\/v2\/media\/1757"}],"wp:attachment":[{"href":"https:\/\/www.hwlegend.tech\/overclock\/wp-json\/wp\/v2\/media?parent=1752"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hwlegend.tech\/overclock\/wp-json\/wp\/v2\/categories?post=1752"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}