{"id":1764,"date":"2020-01-05T00:02:18","date_gmt":"2020-01-04T23:02:18","guid":{"rendered":"https:\/\/www.hwlegend.tech\/overclock\/?p=1764"},"modified":"2020-01-05T00:03:11","modified_gmt":"2020-01-04T23:03:11","slug":"tantissimi-auguri-di-una-buona-epifania-2020-da-tutto-lo-staff-di-hw-legend","status":"publish","type":"post","link":"https:\/\/www.hwlegend.tech\/overclock\/varie\/news\/tantissimi-auguri-di-una-buona-epifania-2020-da-tutto-lo-staff-di-hw-legend\/","title":{"rendered":"Tantissimi auguri di una buona Epifania 2020 da tutto lo staff di HW Legend!"},"content":{"rendered":"<p>Un sincero augurio di una meravigliosa e serena <strong>Epifania 2020<\/strong>, a voi e alle vostre famiglie, da parte di tutto lo staff di <strong>HW Legend<\/strong>. Se hai un sogno e un desiderio da realizzare, chiudi gli occhi e la vecchia signora dall&#8217;aria burlona ti verr\u00e0 a cercare per donarti un momento magico e festoso, ricco di strepitose fantasie. Realizzando tutto ci\u00f2 che di bello hai nel cuore. Ti auguriamo una buona festa dell&#8217;epifania!<\/p>\n<hr \/>\n<p><a href=\"https:\/\/www.hwlegend.tech\/wp-content\/uploads\/2020\/01\/Tantissimi-auguri-di-una-buona-Epifania-2019-da-tutto-lo-staff-di-HW-Legend.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-143643\" src=\"https:\/\/www.hwlegend.tech\/wp-content\/uploads\/2020\/01\/Tantissimi-auguri-di-una-buona-Epifania-2019-da-tutto-lo-staff-di-HW-Legend-1024x576.jpg\" alt=\"\" width=\"1024\" height=\"576\" \/><\/a><\/p>\n<p>Che la vostra calza sia sempre piena di dolci e la vostra anima piena di sogni e di desideri da realizzare! Buona Befana!<\/p>\n<hr \/>\n<p style=\"text-align: center\"><strong>HW Legend Overclock Staff<\/strong><\/p>\n<div class=\"gsp_post_data\" \r\n\t            data-post_type=\"post\" \r\n\t            data-cat=\"news\" \r\n\t            data-modified=\"120\"\r\n\t            data-created=\"1578182538\"\r\n\t            data-title=\"Tantissimi auguri di una buona Epifania 2020 da tutto lo staff di HW Legend!\" \r\n\t            data-home=\"https:\/\/www.hwlegend.tech\/overclock\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Un sincero augurio di una meravigliosa e serena Epifania 2020, a voi e alle vostre famiglie, da parte di tutto lo staff di HW Legend. Se hai un sogno e un desiderio da realizzare, chiudi gli occhi e la vecchia signora dall&#8217;aria burlona ti verr\u00e0 a cercare per donarti un momento magico e festoso, ricco [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1765,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"class_list":["post-1764","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tantissimi auguri di una buona Epifania 2020 da tutto lo staff di HW Legend! - HW Legend Overclock<\/title>\n<meta name=\"description\" content=\"Un sincero augurio di una meravigliosa e serena Epifania 2020, a voi e alle vostre famiglie, da parte di tutto lo staff di HW Legend.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hwlegend.tech\/news\/varie\/tantissimi-auguri-di-una-buona-epifania-2020-da-tutto-lo-staff-di-hw-legend\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tantissimi auguri di una buona Epifania 2020 da tutto lo staff di HW Legend! - HW Legend Overclock\" \/>\n<meta property=\"og:description\" content=\"Un sincero augurio di una meravigliosa e serena Epifania 2020, a voi e alle vostre famiglie, da parte di tutto lo staff di HW Legend.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hwlegend.tech\/news\/varie\/tantissimi-auguri-di-una-buona-epifania-2020-da-tutto-lo-staff-di-hw-legend\/\" \/>\n<meta property=\"og:site_name\" content=\"HW Legend Overclock\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-04T23:02:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-01-04T23:03:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hwlegend.tech\/overclock\/wp-content\/uploads\/sites\/4\/2020\/01\/Cop-Tantissimi-auguri-di-una-buona-Epifania-2019-da-tutto-lo-staff-di-HW-Legend.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"555\" \/>\n\t<meta property=\"og:image:height\" content=\"410\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"djlegend\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"djlegend\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/news\\\/varie\\\/tantissimi-auguri-di-una-buona-epifania-2020-da-tutto-lo-staff-di-hw-legend\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/varie\\\/news\\\/tantissimi-auguri-di-una-buona-epifania-2020-da-tutto-lo-staff-di-hw-legend\\\/\"},\"author\":{\"name\":\"djlegend\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/#\\\/schema\\\/person\\\/3ed113744596ad4689eacfe0d695fcb4\"},\"headline\":\"Tantissimi auguri di una buona Epifania 2020 da tutto lo staff di HW Legend!\",\"datePublished\":\"2020-01-04T23:02:18+00:00\",\"dateModified\":\"2020-01-04T23:03:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/varie\\\/news\\\/tantissimi-auguri-di-una-buona-epifania-2020-da-tutto-lo-staff-di-hw-legend\\\/\"},\"wordCount\":114,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/news\\\/varie\\\/tantissimi-auguri-di-una-buona-epifania-2020-da-tutto-lo-staff-di-hw-legend\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2020\\\/01\\\/Cop-Tantissimi-auguri-di-una-buona-Epifania-2019-da-tutto-lo-staff-di-HW-Legend.jpg\",\"keywords\":[\"buona epifania\",\"Epifania\",\"Epifania 2020\"],\"articleSection\":[\"News\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.hwlegend.tech\\\/news\\\/varie\\\/tantissimi-auguri-di-una-buona-epifania-2020-da-tutto-lo-staff-di-hw-legend\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/varie\\\/news\\\/tantissimi-auguri-di-una-buona-epifania-2020-da-tutto-lo-staff-di-hw-legend\\\/\",\"url\":\"https:\\\/\\\/www.hwlegend.tech\\\/news\\\/varie\\\/tantissimi-auguri-di-una-buona-epifania-2020-da-tutto-lo-staff-di-hw-legend\\\/\",\"name\":\"Tantissimi auguri di una buona Epifania 2020 da tutto lo staff di HW Legend! - HW Legend Overclock\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/news\\\/varie\\\/tantissimi-auguri-di-una-buona-epifania-2020-da-tutto-lo-staff-di-hw-legend\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/news\\\/varie\\\/tantissimi-auguri-di-una-buona-epifania-2020-da-tutto-lo-staff-di-hw-legend\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2020\\\/01\\\/Cop-Tantissimi-auguri-di-una-buona-Epifania-2019-da-tutto-lo-staff-di-HW-Legend.jpg\",\"datePublished\":\"2020-01-04T23:02:18+00:00\",\"dateModified\":\"2020-01-04T23:03:11+00:00\",\"description\":\"Un sincero augurio di una meravigliosa e serena Epifania 2020, a voi e alle vostre famiglie, da parte di tutto lo staff di HW Legend.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/news\\\/varie\\\/tantissimi-auguri-di-una-buona-epifania-2020-da-tutto-lo-staff-di-hw-legend\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hwlegend.tech\\\/news\\\/varie\\\/tantissimi-auguri-di-una-buona-epifania-2020-da-tutto-lo-staff-di-hw-legend\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/news\\\/varie\\\/tantissimi-auguri-di-una-buona-epifania-2020-da-tutto-lo-staff-di-hw-legend\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2020\\\/01\\\/Cop-Tantissimi-auguri-di-una-buona-Epifania-2019-da-tutto-lo-staff-di-HW-Legend.jpg\",\"contentUrl\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2020\\\/01\\\/Cop-Tantissimi-auguri-di-una-buona-Epifania-2019-da-tutto-lo-staff-di-HW-Legend.jpg\",\"width\":555,\"height\":410,\"caption\":\"Created with GIMP\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/news\\\/varie\\\/tantissimi-auguri-di-una-buona-epifania-2020-da-tutto-lo-staff-di-hw-legend\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tantissimi auguri di una buona Epifania 2020 da tutto lo staff di HW Legend!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/#website\",\"url\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/\",\"name\":\"HW Legend Overclock\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/#organization\",\"name\":\"HW Legend Overclock\",\"url\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/05\\\/Logo-OC-finale-trasparente.webp\",\"contentUrl\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/05\\\/Logo-OC-finale-trasparente.webp\",\"width\":700,\"height\":245,\"caption\":\"HW Legend Overclock\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/#\\\/schema\\\/person\\\/3ed113744596ad4689eacfe0d695fcb4\",\"name\":\"djlegend\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d482afe0f6886eac7c042c0145bd9cf53427dcba7126ebb7feadae6e1c03b1ca?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d482afe0f6886eac7c042c0145bd9cf53427dcba7126ebb7feadae6e1c03b1ca?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d482afe0f6886eac7c042c0145bd9cf53427dcba7126ebb7feadae6e1c03b1ca?s=96&d=mm&r=g\",\"caption\":\"djlegend\"},\"url\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/author\\\/djlegend\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tantissimi auguri di una buona Epifania 2020 da tutto lo staff di HW Legend! - HW Legend Overclock","description":"Un sincero augurio di una meravigliosa e serena Epifania 2020, a voi e alle vostre famiglie, da parte di tutto lo staff di HW Legend.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hwlegend.tech\/news\/varie\/tantissimi-auguri-di-una-buona-epifania-2020-da-tutto-lo-staff-di-hw-legend\/","og_locale":"it_IT","og_type":"article","og_title":"Tantissimi auguri di una buona Epifania 2020 da tutto lo staff di HW Legend! - HW Legend Overclock","og_description":"Un sincero augurio di una meravigliosa e serena Epifania 2020, a voi e alle vostre famiglie, da parte di tutto lo staff di HW Legend.","og_url":"https:\/\/www.hwlegend.tech\/news\/varie\/tantissimi-auguri-di-una-buona-epifania-2020-da-tutto-lo-staff-di-hw-legend\/","og_site_name":"HW Legend Overclock","article_published_time":"2020-01-04T23:02:18+00:00","article_modified_time":"2020-01-04T23:03:11+00:00","og_image":[{"width":555,"height":410,"url":"https:\/\/www.hwlegend.tech\/overclock\/wp-content\/uploads\/sites\/4\/2020\/01\/Cop-Tantissimi-auguri-di-una-buona-Epifania-2019-da-tutto-lo-staff-di-HW-Legend.jpg","type":"image\/jpeg"}],"author":"djlegend","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"djlegend"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.hwlegend.tech\/news\/varie\/tantissimi-auguri-di-una-buona-epifania-2020-da-tutto-lo-staff-di-hw-legend\/#article","isPartOf":{"@id":"https:\/\/www.hwlegend.tech\/overclock\/varie\/news\/tantissimi-auguri-di-una-buona-epifania-2020-da-tutto-lo-staff-di-hw-legend\/"},"author":{"name":"djlegend","@id":"https:\/\/www.hwlegend.tech\/overclock\/#\/schema\/person\/3ed113744596ad4689eacfe0d695fcb4"},"headline":"Tantissimi auguri di una buona Epifania 2020 da tutto lo staff di HW Legend!","datePublished":"2020-01-04T23:02:18+00:00","dateModified":"2020-01-04T23:03:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.hwlegend.tech\/overclock\/varie\/news\/tantissimi-auguri-di-una-buona-epifania-2020-da-tutto-lo-staff-di-hw-legend\/"},"wordCount":114,"commentCount":0,"publisher":{"@id":"https:\/\/www.hwlegend.tech\/overclock\/#organization"},"image":{"@id":"https:\/\/www.hwlegend.tech\/news\/varie\/tantissimi-auguri-di-una-buona-epifania-2020-da-tutto-lo-staff-di-hw-legend\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hwlegend.tech\/overclock\/wp-content\/uploads\/sites\/4\/2020\/01\/Cop-Tantissimi-auguri-di-una-buona-Epifania-2019-da-tutto-lo-staff-di-HW-Legend.jpg","keywords":["buona epifania","Epifania","Epifania 2020"],"articleSection":["News"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.hwlegend.tech\/news\/varie\/tantissimi-auguri-di-una-buona-epifania-2020-da-tutto-lo-staff-di-hw-legend\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.hwlegend.tech\/overclock\/varie\/news\/tantissimi-auguri-di-una-buona-epifania-2020-da-tutto-lo-staff-di-hw-legend\/","url":"https:\/\/www.hwlegend.tech\/news\/varie\/tantissimi-auguri-di-una-buona-epifania-2020-da-tutto-lo-staff-di-hw-legend\/","name":"Tantissimi auguri di una buona Epifania 2020 da tutto lo staff di HW Legend! - HW Legend Overclock","isPartOf":{"@id":"https:\/\/www.hwlegend.tech\/overclock\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hwlegend.tech\/news\/varie\/tantissimi-auguri-di-una-buona-epifania-2020-da-tutto-lo-staff-di-hw-legend\/#primaryimage"},"image":{"@id":"https:\/\/www.hwlegend.tech\/news\/varie\/tantissimi-auguri-di-una-buona-epifania-2020-da-tutto-lo-staff-di-hw-legend\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hwlegend.tech\/overclock\/wp-content\/uploads\/sites\/4\/2020\/01\/Cop-Tantissimi-auguri-di-una-buona-Epifania-2019-da-tutto-lo-staff-di-HW-Legend.jpg","datePublished":"2020-01-04T23:02:18+00:00","dateModified":"2020-01-04T23:03:11+00:00","description":"Un sincero augurio di una meravigliosa e serena Epifania 2020, a voi e alle vostre famiglie, da parte di tutto lo staff di HW Legend.","breadcrumb":{"@id":"https:\/\/www.hwlegend.tech\/news\/varie\/tantissimi-auguri-di-una-buona-epifania-2020-da-tutto-lo-staff-di-hw-legend\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hwlegend.tech\/news\/varie\/tantissimi-auguri-di-una-buona-epifania-2020-da-tutto-lo-staff-di-hw-legend\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.hwlegend.tech\/news\/varie\/tantissimi-auguri-di-una-buona-epifania-2020-da-tutto-lo-staff-di-hw-legend\/#primaryimage","url":"https:\/\/www.hwlegend.tech\/overclock\/wp-content\/uploads\/sites\/4\/2020\/01\/Cop-Tantissimi-auguri-di-una-buona-Epifania-2019-da-tutto-lo-staff-di-HW-Legend.jpg","contentUrl":"https:\/\/www.hwlegend.tech\/overclock\/wp-content\/uploads\/sites\/4\/2020\/01\/Cop-Tantissimi-auguri-di-una-buona-Epifania-2019-da-tutto-lo-staff-di-HW-Legend.jpg","width":555,"height":410,"caption":"Created with GIMP"},{"@type":"BreadcrumbList","@id":"https:\/\/www.hwlegend.tech\/news\/varie\/tantissimi-auguri-di-una-buona-epifania-2020-da-tutto-lo-staff-di-hw-legend\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.hwlegend.tech\/overclock\/"},{"@type":"ListItem","position":2,"name":"Tantissimi auguri di una buona Epifania 2020 da tutto lo staff di HW Legend!"}]},{"@type":"WebSite","@id":"https:\/\/www.hwlegend.tech\/overclock\/#website","url":"https:\/\/www.hwlegend.tech\/overclock\/","name":"HW Legend Overclock","description":"","publisher":{"@id":"https:\/\/www.hwlegend.tech\/overclock\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hwlegend.tech\/overclock\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.hwlegend.tech\/overclock\/#organization","name":"HW Legend Overclock","url":"https:\/\/www.hwlegend.tech\/overclock\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.hwlegend.tech\/overclock\/#\/schema\/logo\/image\/","url":"https:\/\/www.hwlegend.tech\/overclock\/wp-content\/uploads\/sites\/4\/2025\/05\/Logo-OC-finale-trasparente.webp","contentUrl":"https:\/\/www.hwlegend.tech\/overclock\/wp-content\/uploads\/sites\/4\/2025\/05\/Logo-OC-finale-trasparente.webp","width":700,"height":245,"caption":"HW Legend Overclock"},"image":{"@id":"https:\/\/www.hwlegend.tech\/overclock\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.hwlegend.tech\/overclock\/#\/schema\/person\/3ed113744596ad4689eacfe0d695fcb4","name":"djlegend","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/d482afe0f6886eac7c042c0145bd9cf53427dcba7126ebb7feadae6e1c03b1ca?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d482afe0f6886eac7c042c0145bd9cf53427dcba7126ebb7feadae6e1c03b1ca?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d482afe0f6886eac7c042c0145bd9cf53427dcba7126ebb7feadae6e1c03b1ca?s=96&d=mm&r=g","caption":"djlegend"},"url":"https:\/\/www.hwlegend.tech\/overclock\/author\/djlegend\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hwlegend.tech\/overclock\/wp-json\/wp\/v2\/posts\/1764","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hwlegend.tech\/overclock\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hwlegend.tech\/overclock\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hwlegend.tech\/overclock\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hwlegend.tech\/overclock\/wp-json\/wp\/v2\/comments?post=1764"}],"version-history":[{"count":1,"href":"https:\/\/www.hwlegend.tech\/overclock\/wp-json\/wp\/v2\/posts\/1764\/revisions"}],"predecessor-version":[{"id":1766,"href":"https:\/\/www.hwlegend.tech\/overclock\/wp-json\/wp\/v2\/posts\/1764\/revisions\/1766"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hwlegend.tech\/overclock\/wp-json\/wp\/v2\/media\/1765"}],"wp:attachment":[{"href":"https:\/\/www.hwlegend.tech\/overclock\/wp-json\/wp\/v2\/media?parent=1764"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hwlegend.tech\/overclock\/wp-json\/wp\/v2\/categories?post=1764"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}