{"id":1784,"date":"2020-01-07T21:39:41","date_gmt":"2020-01-07T20:39:41","guid":{"rendered":"https:\/\/www.hwlegend.tech\/overclock\/?p=1784"},"modified":"2020-01-07T21:40:08","modified_gmt":"2020-01-07T20:40:08","slug":"ces-2020-intel-svela-le-cpu-tiger-lake-a-10nm-e-la-gpu-discreta-denominata-dg1","status":"publish","type":"post","link":"https:\/\/www.hwlegend.tech\/overclock\/varie\/news\/ces-2020-intel-svela-le-cpu-tiger-lake-a-10nm-e-la-gpu-discreta-denominata-dg1\/","title":{"rendered":"[CES 2020] Intel svela le CPU Tiger Lake a 10nm+ e la GPU discreta denominata DG1"},"content":{"rendered":"<p><strong>Intel<\/strong> <a href=\"https:\/\/newsroom.intel.com\/press-kits\/2020-ces\/#gs.qcgnhi\" target=\"_blank\" rel=\"noopener noreferrer\">direttamente<\/a> dal <strong>CES 2020<\/strong> di <strong>Las Vegas<\/strong> ha svelato le nuove CPU per notebook di undicesima generazione denominate <strong>Tiger Lake<\/strong> e la prima scheda video discreta denominata <strong>DG1<\/strong>.<\/p>\n<hr \/>\n<p><a href=\"https:\/\/www.hwlegend.tech\/wp-content\/uploads\/2020\/01\/CES-2020-Intel-svela-le-CPU-Tiger-Lake-a-10nm-e-la-GPU-discreta-denominata-DG1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-143834\" src=\"https:\/\/www.hwlegend.tech\/wp-content\/uploads\/2020\/01\/CES-2020-Intel-svela-le-CPU-Tiger-Lake-a-10nm-e-la-GPU-discreta-denominata-DG1-1024x576.jpg\" alt=\"\" width=\"1024\" height=\"576\" \/><\/a><\/p>\n<p>I processori Tiger Lake saranno realizzati con processo produttivo a 10 nm+ e che i primi notebook ad adottarli dovrebbero arrivare in estate. A livello prestazionale dovrebbero apportare, rispetto alla passata generazione, incrementi prestazionali intorno al 10-15% lato CPU e raddoppiare le prestazioni lato GPU integrata, grazie all&#8217;utilizzo della nuova architettura XE.<\/p>\n<p><a href=\"https:\/\/www.hwlegend.tech\/wp-content\/uploads\/2020\/01\/CES-2020-Intel-svela-le-CPU-Tiger-Lake-a-10nm-e-la-GPU-discreta-denominata-DG1-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-143835\" src=\"https:\/\/www.hwlegend.tech\/wp-content\/uploads\/2020\/01\/CES-2020-Intel-svela-le-CPU-Tiger-Lake-a-10nm-e-la-GPU-discreta-denominata-DG1-1-1024x576.jpg\" alt=\"\" width=\"1024\" height=\"576\" \/><\/a><\/p>\n<p>Intel inoltre ha parlato brevemente di una belle quattro GPU discrete che dovrebbero essere quasi prossime al debutto. Per la precisione ha fatto vedere velocemente una slide che riguardava il modello denominato DG1, senza rilasciare specifiche o altre informazioni.<\/p>\n<p><a href=\"https:\/\/www.hwlegend.tech\/wp-content\/uploads\/2020\/01\/CES-2020-Intel-svela-le-CPU-Tiger-Lake-a-10nm-e-la-GPU-discreta-denominata-DG1-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-143837\" src=\"https:\/\/www.hwlegend.tech\/wp-content\/uploads\/2020\/01\/CES-2020-Intel-svela-le-CPU-Tiger-Lake-a-10nm-e-la-GPU-discreta-denominata-DG1-2-1024x576.jpg\" alt=\"\" width=\"1024\" height=\"576\" \/><\/a><\/p>\n<p>Il CEO di Intel Bob Swan ha inoltre comunicato una serie di aggiornamenti relativi a Mobileye, inclusa una <a href=\"https:\/\/youtu.be\/-kNUVM8s0nc\">dimostrazione<\/a> della RoboCar a guida autonoma in movimento nel traffico in maniera naturale. La prova ha dimostrato l\u2019approccio unico e innovativo di Mobileye per offrire mobilit\u00e0 pi\u00f9 sicura per tutti con una combinazione di intelligenza artificiale, computer vision, il modello scientifico-normativo <a href=\"https:\/\/newsroom.intel.com\/articles\/rss-explained-five-rules-autonomous-vehicle-safety\/\">RSS<\/a> e una ridondanza reale attraverso l\u2019uso di sistemi di rilevazione sensoristica indipendenti.<\/p>\n<p>Swan ha anche sottolineato la collaborazione di Intel con la <a href=\"https:\/\/newsroom.intel.com\/news\/american-red-cross-intel-use-ai-disaster-preparedness\/\">Croce Rossa Americana<\/a> e il suo progetto per migliorare la capacit\u00e0 di intervento nel corso di catastrofi, Missing Maps. Utilizzando l\u2019accelerazione di AI integrata nei processori Intel Xeon Scalable di seconda generazione, Intel aiuta la Croce Rossa Americana e il suo progetto Missing Maps nella creazione di mappe estremamente accurate, complete di ponti e strade, per le aree remote del mondo in cui mancano queste imortanti informazioni, aiutando in questo modo i soccorritori ad intervenire in caso di calamit\u00e0.<\/p>\n<p>\u201cLa nostra ambizione in Intel \u00e8 di aiutare i clienti a sfruttare al massimo le innovazioni tecnologiche, come l\u2019intelligenza artificiale, il 5G e l\u2019edge, in modo che, insieme, possiamo arricchire le vite e costruire il mondo dei prossimi decenni. Come abbiamo evidenziato oggi, il nostro obiettivo di infondere intelligenza in ogni aspetto dell&#8217;informatica pu\u00f2 avere un impatto positivo con una portata senza precedenti\u201d, ha dichiarato Swan.<\/p>\n<p>Il data center \u00e8 la forza trainante che fornisce intelligenza alle aziende di tutto il mondo e i processori scalabili Intel Xeon continuano a costituire le fondamenta dei data center. Navin Shenoy, Executive Vice President di Intel, ha annunciato che i processori Intel Xeon Scalable di terza generazione, in arrivo nella prima met\u00e0 del 2020, includeranno nuove estensioni di Intel DL Boost per offrire accelerazione integrata dell\u2019addestramento dell\u2019intelligenza artificiale, che fornir\u00e0 fino al 60% di incremento delle prestazioni di training rispetto alla precedente famiglia di processori.<\/p>\n<p>Shenoy ha evidenziato diversi modi in cui Intel sta infondendo intelligenza nelle piattaforme di dati in ambito cloud, rete ed edge, e come tutto questo sta trasformando lo sport e l\u2019intrattenimento:<\/p>\n<hr \/>\n<ul>\n<li><strong>Netflix ottimizza e accelera i servizi di streaming:<\/strong> Netflix ha utilizzato la pi\u00f9 recente tecnologia di compressione video, AV1, per migliorare i servizi streaming e per portare contenuti in tutto il mondo con efficienza di compressione fino al 60% superiore rispetto alla precedente tecnologia (AVC). L\u2019impegno congiunto di Intel e Netflix continua con lo sviluppo di una codifica open-source ad altre prestazioni (SVT-AV1) ottimzzata sui processori Intel Xeon Scalable di seconda generazione, che offrono guadagni significativi in qualit\u00e0 e performance rendendola un\u2019opzione praticabile per l\u2019implementazione commerciale.<\/li>\n<li><strong>Esperienze migliorate per atleti e spettatori dei Giochi Olimpici di Tokyo 2020 con 3D Athlete Tracking:<\/strong> 3D Athlete Tracking (3DAT) \u00e8 una soluzione di visione artificiale unica nel suo genere che impiega l\u2019intelligenza artificiale per migliorare l&#8217;esperienza visiva con dati e immagini quasi in tempo reale. 3DAT utilizza telecamere estremamente mobili per catturare la forma e il movimento degli atleti, applicando quindi algoritmi ottimizzati con Intel DL Boost e potenziati dai processori Intel Xeon Scalable per analizzare la biomeccanica dei movimenti degli atleti. Shenoy ha annunciato che questa tecnologia migliorer\u00e0 i replay dei 100 metri e di altre gare di velocit\u00e0 dei Giochi olimpici di Tokyo 2020.<\/li>\n<li><strong>Streaming video volumetrico, su larga scala:<\/strong> Intel e il mondo dello sport stanno trasformando l&#8217;esperienza di visione degli eventi sportivi grazie al video volumetrico, un importante progresso sulla strada che porta all\u2019abattimento dei limiti nell\u2018esperienza di visione dello sport. Intel True View riproduce sinteticamente in cloud l&#8217;intero volume del campo da gioco degli stadi, per offrire infinite angolazioni che consentano ai tifosi di scegliere qualsiasi punto di vista e la prospettiva di ciascun giocatore, guardando in streaming sui loro dispositivi. Intel e la NFL hanno mostrato la potenza del video volumetrico in streaming con un match della Week 15, Cleveland Browns vs Arizona Cardinals. I dati prodotti nel primo quarto di una sola partita NFL superano i 3 TB al minuto, un incremento esponenziale che richiede un&#8217;enorme potenza di calcolo.<\/li>\n<\/ul>\n<hr \/>\n<p style=\"text-align: center\"><strong>HW Legend Overclock Staff<\/strong><\/p>\n<div class=\"gsp_post_data\" \r\n\t            data-post_type=\"post\" \r\n\t            data-cat=\"news\" \r\n\t            data-modified=\"120\"\r\n\t            data-created=\"1578433181\"\r\n\t            data-title=\"[CES 2020] Intel svela le CPU Tiger Lake a 10nm+ e la GPU discreta denominata DG1\" \r\n\t            data-home=\"https:\/\/www.hwlegend.tech\/overclock\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Intel direttamente dal CES 2020 di Las Vegas ha svelato le nuove CPU per notebook di undicesima generazione denominate Tiger Lake e la prima scheda video discreta denominata DG1. I processori Tiger Lake saranno realizzati con processo produttivo a 10 nm+ e che i primi notebook ad adottarli dovrebbero arrivare in estate. A livello prestazionale [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1785,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"class_list":["post-1784","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>[CES 2020] Intel svela le CPU Tiger Lake a 10nm+ e la GPU discreta denominata DG1 - HW Legend Overclock<\/title>\n<meta name=\"description\" content=\"Intel dal CES 2020 di Las Vegas ha svelato le nuove CPU per notebook denominate Tiger Lake e la prima scheda video discreta denominata DG1.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hwlegend.tech\/news\/hardware\/ces-2020-intel-svela-le-cpu-tiger-lake-a-10nm-e-la-gpu-discreta-denominata-dg1\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[CES 2020] Intel svela le CPU Tiger Lake a 10nm+ e la GPU discreta denominata DG1 - HW Legend Overclock\" \/>\n<meta property=\"og:description\" content=\"Intel dal CES 2020 di Las Vegas ha svelato le nuove CPU per notebook denominate Tiger Lake e la prima scheda video discreta denominata DG1.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hwlegend.tech\/news\/hardware\/ces-2020-intel-svela-le-cpu-tiger-lake-a-10nm-e-la-gpu-discreta-denominata-dg1\/\" \/>\n<meta property=\"og:site_name\" content=\"HW Legend Overclock\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-07T20:39:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-01-07T20:40:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hwlegend.tech\/overclock\/wp-content\/uploads\/sites\/4\/2020\/01\/Cop-CES-2020-Intel-svela-le-CPU-Tiger-Lake-a-10nm-e-la-GPU-discreta-denominata-DG1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"555\" \/>\n\t<meta property=\"og:image:height\" content=\"410\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"djlegend\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"djlegend\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/news\\\/hardware\\\/ces-2020-intel-svela-le-cpu-tiger-lake-a-10nm-e-la-gpu-discreta-denominata-dg1\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/varie\\\/news\\\/ces-2020-intel-svela-le-cpu-tiger-lake-a-10nm-e-la-gpu-discreta-denominata-dg1\\\/\"},\"author\":{\"name\":\"djlegend\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/#\\\/schema\\\/person\\\/3ed113744596ad4689eacfe0d695fcb4\"},\"headline\":\"[CES 2020] Intel svela le CPU Tiger Lake a 10nm+ e la GPU discreta denominata DG1\",\"datePublished\":\"2020-01-07T20:39:41+00:00\",\"dateModified\":\"2020-01-07T20:40:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/varie\\\/news\\\/ces-2020-intel-svela-le-cpu-tiger-lake-a-10nm-e-la-gpu-discreta-denominata-dg1\\\/\"},\"wordCount\":813,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/news\\\/hardware\\\/ces-2020-intel-svela-le-cpu-tiger-lake-a-10nm-e-la-gpu-discreta-denominata-dg1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2020\\\/01\\\/Cop-CES-2020-Intel-svela-le-CPU-Tiger-Lake-a-10nm-e-la-GPU-discreta-denominata-DG1.jpg\",\"keywords\":[\"CES 2020\",\"CPU\",\"DG1\",\"Intel\",\"Las Vegas\",\"processori\",\"Tiger Lake\"],\"articleSection\":[\"News\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.hwlegend.tech\\\/news\\\/hardware\\\/ces-2020-intel-svela-le-cpu-tiger-lake-a-10nm-e-la-gpu-discreta-denominata-dg1\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/varie\\\/news\\\/ces-2020-intel-svela-le-cpu-tiger-lake-a-10nm-e-la-gpu-discreta-denominata-dg1\\\/\",\"url\":\"https:\\\/\\\/www.hwlegend.tech\\\/news\\\/hardware\\\/ces-2020-intel-svela-le-cpu-tiger-lake-a-10nm-e-la-gpu-discreta-denominata-dg1\\\/\",\"name\":\"[CES 2020] Intel svela le CPU Tiger Lake a 10nm+ e la GPU discreta denominata DG1 - HW Legend Overclock\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/news\\\/hardware\\\/ces-2020-intel-svela-le-cpu-tiger-lake-a-10nm-e-la-gpu-discreta-denominata-dg1\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/news\\\/hardware\\\/ces-2020-intel-svela-le-cpu-tiger-lake-a-10nm-e-la-gpu-discreta-denominata-dg1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2020\\\/01\\\/Cop-CES-2020-Intel-svela-le-CPU-Tiger-Lake-a-10nm-e-la-GPU-discreta-denominata-DG1.jpg\",\"datePublished\":\"2020-01-07T20:39:41+00:00\",\"dateModified\":\"2020-01-07T20:40:08+00:00\",\"description\":\"Intel dal CES 2020 di Las Vegas ha svelato le nuove CPU per notebook denominate Tiger Lake e la prima scheda video discreta denominata DG1.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/news\\\/hardware\\\/ces-2020-intel-svela-le-cpu-tiger-lake-a-10nm-e-la-gpu-discreta-denominata-dg1\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hwlegend.tech\\\/news\\\/hardware\\\/ces-2020-intel-svela-le-cpu-tiger-lake-a-10nm-e-la-gpu-discreta-denominata-dg1\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/news\\\/hardware\\\/ces-2020-intel-svela-le-cpu-tiger-lake-a-10nm-e-la-gpu-discreta-denominata-dg1\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2020\\\/01\\\/Cop-CES-2020-Intel-svela-le-CPU-Tiger-Lake-a-10nm-e-la-GPU-discreta-denominata-DG1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2020\\\/01\\\/Cop-CES-2020-Intel-svela-le-CPU-Tiger-Lake-a-10nm-e-la-GPU-discreta-denominata-DG1.jpg\",\"width\":555,\"height\":410},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/news\\\/hardware\\\/ces-2020-intel-svela-le-cpu-tiger-lake-a-10nm-e-la-gpu-discreta-denominata-dg1\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"[CES 2020] Intel svela le CPU Tiger Lake a 10nm+ e la GPU discreta denominata DG1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/#website\",\"url\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/\",\"name\":\"HW Legend Overclock\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/#organization\",\"name\":\"HW Legend Overclock\",\"url\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/05\\\/Logo-OC-finale-trasparente.webp\",\"contentUrl\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/05\\\/Logo-OC-finale-trasparente.webp\",\"width\":700,\"height\":245,\"caption\":\"HW Legend Overclock\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/#\\\/schema\\\/person\\\/3ed113744596ad4689eacfe0d695fcb4\",\"name\":\"djlegend\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d482afe0f6886eac7c042c0145bd9cf53427dcba7126ebb7feadae6e1c03b1ca?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d482afe0f6886eac7c042c0145bd9cf53427dcba7126ebb7feadae6e1c03b1ca?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d482afe0f6886eac7c042c0145bd9cf53427dcba7126ebb7feadae6e1c03b1ca?s=96&d=mm&r=g\",\"caption\":\"djlegend\"},\"url\":\"https:\\\/\\\/www.hwlegend.tech\\\/overclock\\\/author\\\/djlegend\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[CES 2020] Intel svela le CPU Tiger Lake a 10nm+ e la GPU discreta denominata DG1 - HW Legend Overclock","description":"Intel dal CES 2020 di Las Vegas ha svelato le nuove CPU per notebook denominate Tiger Lake e la prima scheda video discreta denominata DG1.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hwlegend.tech\/news\/hardware\/ces-2020-intel-svela-le-cpu-tiger-lake-a-10nm-e-la-gpu-discreta-denominata-dg1\/","og_locale":"it_IT","og_type":"article","og_title":"[CES 2020] Intel svela le CPU Tiger Lake a 10nm+ e la GPU discreta denominata DG1 - HW Legend Overclock","og_description":"Intel dal CES 2020 di Las Vegas ha svelato le nuove CPU per notebook denominate Tiger Lake e la prima scheda video discreta denominata DG1.","og_url":"https:\/\/www.hwlegend.tech\/news\/hardware\/ces-2020-intel-svela-le-cpu-tiger-lake-a-10nm-e-la-gpu-discreta-denominata-dg1\/","og_site_name":"HW Legend Overclock","article_published_time":"2020-01-07T20:39:41+00:00","article_modified_time":"2020-01-07T20:40:08+00:00","og_image":[{"width":555,"height":410,"url":"https:\/\/www.hwlegend.tech\/overclock\/wp-content\/uploads\/sites\/4\/2020\/01\/Cop-CES-2020-Intel-svela-le-CPU-Tiger-Lake-a-10nm-e-la-GPU-discreta-denominata-DG1.jpg","type":"image\/jpeg"}],"author":"djlegend","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"djlegend","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.hwlegend.tech\/news\/hardware\/ces-2020-intel-svela-le-cpu-tiger-lake-a-10nm-e-la-gpu-discreta-denominata-dg1\/#article","isPartOf":{"@id":"https:\/\/www.hwlegend.tech\/overclock\/varie\/news\/ces-2020-intel-svela-le-cpu-tiger-lake-a-10nm-e-la-gpu-discreta-denominata-dg1\/"},"author":{"name":"djlegend","@id":"https:\/\/www.hwlegend.tech\/overclock\/#\/schema\/person\/3ed113744596ad4689eacfe0d695fcb4"},"headline":"[CES 2020] Intel svela le CPU Tiger Lake a 10nm+ e la GPU discreta denominata DG1","datePublished":"2020-01-07T20:39:41+00:00","dateModified":"2020-01-07T20:40:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.hwlegend.tech\/overclock\/varie\/news\/ces-2020-intel-svela-le-cpu-tiger-lake-a-10nm-e-la-gpu-discreta-denominata-dg1\/"},"wordCount":813,"commentCount":0,"publisher":{"@id":"https:\/\/www.hwlegend.tech\/overclock\/#organization"},"image":{"@id":"https:\/\/www.hwlegend.tech\/news\/hardware\/ces-2020-intel-svela-le-cpu-tiger-lake-a-10nm-e-la-gpu-discreta-denominata-dg1\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hwlegend.tech\/overclock\/wp-content\/uploads\/sites\/4\/2020\/01\/Cop-CES-2020-Intel-svela-le-CPU-Tiger-Lake-a-10nm-e-la-GPU-discreta-denominata-DG1.jpg","keywords":["CES 2020","CPU","DG1","Intel","Las Vegas","processori","Tiger Lake"],"articleSection":["News"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.hwlegend.tech\/news\/hardware\/ces-2020-intel-svela-le-cpu-tiger-lake-a-10nm-e-la-gpu-discreta-denominata-dg1\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.hwlegend.tech\/overclock\/varie\/news\/ces-2020-intel-svela-le-cpu-tiger-lake-a-10nm-e-la-gpu-discreta-denominata-dg1\/","url":"https:\/\/www.hwlegend.tech\/news\/hardware\/ces-2020-intel-svela-le-cpu-tiger-lake-a-10nm-e-la-gpu-discreta-denominata-dg1\/","name":"[CES 2020] Intel svela le CPU Tiger Lake a 10nm+ e la GPU discreta denominata DG1 - HW Legend Overclock","isPartOf":{"@id":"https:\/\/www.hwlegend.tech\/overclock\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hwlegend.tech\/news\/hardware\/ces-2020-intel-svela-le-cpu-tiger-lake-a-10nm-e-la-gpu-discreta-denominata-dg1\/#primaryimage"},"image":{"@id":"https:\/\/www.hwlegend.tech\/news\/hardware\/ces-2020-intel-svela-le-cpu-tiger-lake-a-10nm-e-la-gpu-discreta-denominata-dg1\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hwlegend.tech\/overclock\/wp-content\/uploads\/sites\/4\/2020\/01\/Cop-CES-2020-Intel-svela-le-CPU-Tiger-Lake-a-10nm-e-la-GPU-discreta-denominata-DG1.jpg","datePublished":"2020-01-07T20:39:41+00:00","dateModified":"2020-01-07T20:40:08+00:00","description":"Intel dal CES 2020 di Las Vegas ha svelato le nuove CPU per notebook denominate Tiger Lake e la prima scheda video discreta denominata DG1.","breadcrumb":{"@id":"https:\/\/www.hwlegend.tech\/news\/hardware\/ces-2020-intel-svela-le-cpu-tiger-lake-a-10nm-e-la-gpu-discreta-denominata-dg1\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hwlegend.tech\/news\/hardware\/ces-2020-intel-svela-le-cpu-tiger-lake-a-10nm-e-la-gpu-discreta-denominata-dg1\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.hwlegend.tech\/news\/hardware\/ces-2020-intel-svela-le-cpu-tiger-lake-a-10nm-e-la-gpu-discreta-denominata-dg1\/#primaryimage","url":"https:\/\/www.hwlegend.tech\/overclock\/wp-content\/uploads\/sites\/4\/2020\/01\/Cop-CES-2020-Intel-svela-le-CPU-Tiger-Lake-a-10nm-e-la-GPU-discreta-denominata-DG1.jpg","contentUrl":"https:\/\/www.hwlegend.tech\/overclock\/wp-content\/uploads\/sites\/4\/2020\/01\/Cop-CES-2020-Intel-svela-le-CPU-Tiger-Lake-a-10nm-e-la-GPU-discreta-denominata-DG1.jpg","width":555,"height":410},{"@type":"BreadcrumbList","@id":"https:\/\/www.hwlegend.tech\/news\/hardware\/ces-2020-intel-svela-le-cpu-tiger-lake-a-10nm-e-la-gpu-discreta-denominata-dg1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.hwlegend.tech\/overclock\/"},{"@type":"ListItem","position":2,"name":"[CES 2020] Intel svela le CPU Tiger Lake a 10nm+ e la GPU discreta denominata DG1"}]},{"@type":"WebSite","@id":"https:\/\/www.hwlegend.tech\/overclock\/#website","url":"https:\/\/www.hwlegend.tech\/overclock\/","name":"HW Legend Overclock","description":"","publisher":{"@id":"https:\/\/www.hwlegend.tech\/overclock\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hwlegend.tech\/overclock\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.hwlegend.tech\/overclock\/#organization","name":"HW Legend Overclock","url":"https:\/\/www.hwlegend.tech\/overclock\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.hwlegend.tech\/overclock\/#\/schema\/logo\/image\/","url":"https:\/\/www.hwlegend.tech\/overclock\/wp-content\/uploads\/sites\/4\/2025\/05\/Logo-OC-finale-trasparente.webp","contentUrl":"https:\/\/www.hwlegend.tech\/overclock\/wp-content\/uploads\/sites\/4\/2025\/05\/Logo-OC-finale-trasparente.webp","width":700,"height":245,"caption":"HW Legend Overclock"},"image":{"@id":"https:\/\/www.hwlegend.tech\/overclock\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.hwlegend.tech\/overclock\/#\/schema\/person\/3ed113744596ad4689eacfe0d695fcb4","name":"djlegend","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/d482afe0f6886eac7c042c0145bd9cf53427dcba7126ebb7feadae6e1c03b1ca?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d482afe0f6886eac7c042c0145bd9cf53427dcba7126ebb7feadae6e1c03b1ca?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d482afe0f6886eac7c042c0145bd9cf53427dcba7126ebb7feadae6e1c03b1ca?s=96&d=mm&r=g","caption":"djlegend"},"url":"https:\/\/www.hwlegend.tech\/overclock\/author\/djlegend\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hwlegend.tech\/overclock\/wp-json\/wp\/v2\/posts\/1784","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hwlegend.tech\/overclock\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hwlegend.tech\/overclock\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hwlegend.tech\/overclock\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hwlegend.tech\/overclock\/wp-json\/wp\/v2\/comments?post=1784"}],"version-history":[{"count":3,"href":"https:\/\/www.hwlegend.tech\/overclock\/wp-json\/wp\/v2\/posts\/1784\/revisions"}],"predecessor-version":[{"id":1789,"href":"https:\/\/www.hwlegend.tech\/overclock\/wp-json\/wp\/v2\/posts\/1784\/revisions\/1789"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hwlegend.tech\/overclock\/wp-json\/wp\/v2\/media\/1785"}],"wp:attachment":[{"href":"https:\/\/www.hwlegend.tech\/overclock\/wp-json\/wp\/v2\/media?parent=1784"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hwlegend.tech\/overclock\/wp-json\/wp\/v2\/categories?post=1784"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}